{"id":80636,"date":"2021-08-13T11:50:43","date_gmt":"2021-08-13T11:50:43","guid":{"rendered":"https:\/\/wp-staging.amberscript.com\/convert-audio-to-text\/"},"modified":"2023-07-04T16:27:05","modified_gmt":"2023-07-04T14:27:05","slug":"convertir-des-fichiers-audio-en-texte","status":"publish","type":"page","link":"https:\/\/wp-staging.amberscript.com\/fr\/blog\/convertir-des-fichiers-audio-en-texte\/","title":{"rendered":"Convertisseur audio\/texte gratuit | SEO | FR"},"content":{"rendered":"\n<section class=\"block small-slider\">\n   <div class=\"grid-container\">\n      <div class=\"grid-x grid-margin-y align-middle align-left\">\n                     <div class=\"cell small-12 text-center\">\n            <div class=\"subtitle\">\n               Approuv\u00e9 par plus d&rsquo;un million d&rsquo;utilisateurs             <\/div>\n            <div class=\"grid-x grid-margin-x grid-margin-y align-center\">\n               \n                  <div class=\"cell small-6 medium-shrink\">\n                     <div class=\"rating-holder\">\n                        <p class=\"small\">4.3 on Trustpilot<\/p>\n                        <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/stars_trustpilot.svg\"\/>\n                     <\/div>\n                  <\/div>\n                                                <div class=\"cell small-6 medium-shrink\">\n                     <div class=\"rating-holder\">\n                        <p class=\"small\">4.5 on Google<\/p>\n                        <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/stars_google.png\"\/>\n                     <\/div>\n                  <\/div>\n               \n            <\/div>\n         <\/div>\n      \n         <div class=\"cell large-12\">\n\n                  <img decoding=\"async\" width=\"2480\" height=\"148\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2021\/04\/LogoBanner-Transcription-FR.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2021\/04\/LogoBanner-Transcription-FR.png 2480w, https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2021\/04\/LogoBanner-Transcription-FR-640x38.png 640w, https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2021\/04\/LogoBanner-Transcription-FR-1280x76.png 1280w, https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2021\/04\/LogoBanner-Transcription-FR-768x46.png 768w, https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2021\/04\/LogoBanner-Transcription-FR-1536x92.png 1536w, https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2021\/04\/LogoBanner-Transcription-FR-2048x122.png 2048w\" sizes=\"(max-width: 2480px) 100vw, 2480px\" \/>\n         <\/div>\n      <\/div>\n   <\/div>\n<\/section>\n\n<div class=\"block text-image\">\n\t<div class=\"grid-container\">\n      <div class=\"grid-x align-middle grid-margin-y grid-margin-x\">\n\t\t  \n\n        <div class=\"cell medium-6 large-5 medium-order-2 medium-offset-0 large-offset-1\t\">\t\t  \n\n                            <div class=\"image-holder text-center\">\n\n                                    <img decoding=\"async\" width=\"640\" height=\"448\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2022\/02\/amberscript-audio-to-text-online-editor-perfecting-the-text.png\" class=\"img-responsive\" alt=\"screenshot of amberscript audio to text online editor perfecting the text\" \/>                                    <\/div>\n            \t\t\t\n        <\/div>\n\t\t  \n\n        <div class=\"cell medium-6 large-5  \">  \n\n               \n                                                  \n                                                   \n                                   <ol>\n<li><span style=\"text-decoration: underline;\"><a href=\"#comment-convertir-des-fichiers-audio\">Comment convertir des fichiers audio ?<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"#quels-sont-les-fichiers-audio-qui-peuvent-etre-convertis-en-texte\">Quels sont les fichiers audio qui peuvent \u00eatre convertis en texte ?<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"#avantages-et-inconvenients-des-formats-mp3-flac-et-aac\"><span style=\"font-weight: 400;\">Avantages et inconv\u00e9nients des formats MP3, FLAC et AAC<\/span><\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"#secteurs-beneficiant-des-convertisseurs-audio-texte\">Les secteurs b\u00e9n\u00e9ficiant des convertisseurs audio\/texte<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"#comment-nous-convertissons-un-fichier-audio-en-texte\">Comment nous convertissons un fichier audio en texte ?<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"#foire-aux-questions\">Foire aux Questions<\/a><\/span><\/li>\n<\/ol>\n               \n                            \n        <\/div>\n      <\/div>\n   <\/div>\n<\/div>\n\n\n\n\n<!-- \/\/ small -->\n    <div class=\"block usps\">\n\t\t\t<div class=\"grid-container\">\n        <div class=\"grid-x grid-margin-x grid-margin-y  align-center\">\n\n            \n<div class=\"cell large-12 text-center\">\n  <div class=\"title-holder\">\n\n\n\n                          <h6><span id=\"comment-convertir-des-fichiers-audio\"><\/span><\/h6>\n                    \n                                    <h2>Comment convertir un fichier audio en texte<\/h2>\n                      <\/div>           \n<\/div>\n\n                            \n\t\t\t\t\t\t\t<div class=\"cell small-6 large-4\">\n\t\t\t                        <div class=\"usp-item\"\n                                                     >\n                            <div class=\"grid-x grid-margin-x grid-margin-y align-middle\">\n                                                                    <div class=\"cell small-12 text-center justify-center\">\n                                        <div class=\"usp-icon theme-background-secondary \">\n                                                <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2021\/07\/manual-check-icon.png\" alt=\"Transcribing audio to text manually icon\">\n                                        <\/div>\n                                    <\/div>\n                                                                \n                                <div class=\"cell auto\">\n                                    <div class=\"title theme-text-color-primary text-center \">Transcrire soi-m\u00eame<\/div>\n                                <\/div>\n                                <div class=\"cell small-12 text-center\">\n                                    <p>Vous pouvez transcrire votre fichier audio en texte manuellement, \u00e0 l&rsquo;aide d&rsquo;un traitement de texte. Cependant, il faut savoir que la transcription d&rsquo;un fichier audio d&rsquo;une heure peut prendre jusqu&rsquo;\u00e0 6 heures !<\/p>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                \n\t\t\t\t\t\t\t<div class=\"cell small-6 large-4\">\n\t\t\t                        <div class=\"usp-item\"\n                                                     >\n                            <div class=\"grid-x grid-margin-x grid-margin-y align-middle\">\n                                                                    <div class=\"cell small-12 text-center justify-center\">\n                                        <div class=\"usp-icon theme-background-secondary \">\n                                                <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2021\/07\/automatic-transcription-icon.png\" alt=\"Automatic transcription icon\">\n                                        <\/div>\n                                    <\/div>\n                                                                \n                                <div class=\"cell auto\">\n                                    <div class=\"title theme-text-color-primary text-center \">Transcription automatique de fichiers audio en texte<\/div>\n                                <\/div>\n                                <div class=\"cell small-12 text-center\">\n                                    <p>Notre convertisseur audio vers un texte cr\u00e9e automatiquement un premier document et fournit un \u00e9diteur de texte intuitif permettant d&rsquo;am\u00e9liorer le texte soi-m\u00eame. <\/p>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                \n\t\t\t\t\t\t\t<div class=\"cell small-6 large-4\">\n\t\t\t                        <div class=\"usp-item\"\n                                                     >\n                            <div class=\"grid-x grid-margin-x grid-margin-y align-middle\">\n                                                                    <div class=\"cell small-12 text-center justify-center\">\n                                        <div class=\"usp-icon theme-background-secondary \">\n                                                <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2021\/07\/manual-transcription-icon.png\" alt=\"Manual transcription service icon\">\n                                        <\/div>\n                                    <\/div>\n                                                                \n                                <div class=\"cell auto\">\n                                    <div class=\"title theme-text-color-primary text-center \">Obtenir une transcription de fichiers audio fait par des professionnels <\/div>\n                                <\/div>\n                                <div class=\"cell small-12 text-center\">\n                                    <p>Nos transcripteurs professionnels convertissent vos documents audio en texte avec une pr\u00e9cision totale. L&rsquo;\u00e9quipe s&rsquo;appuie sur la technologie pour rendre le processus aussi facile, rapide et abordable que possible. <\/p>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <\/div>\n    <\/div>\n    \n \n    <div class=\"usps-slider hide-for-large\">\n        <div class=\"responsive-slider\">\n                                                <div class=\"carousel-cell usp-item\">\n                        <div class=\"grid-container\">\n                            <div class=\"grid-x align-center align-middle grid-margin-y grid-margin-x\">\n                                <div class=\"cell shrink\">\n                                <div class=\"usp-icon theme-background-secondary \">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2021\/07\/manual-check-icon.png\" alt=\"Transcribing audio to text manually icon\">\n                                                                            <\/div>\n                                <\/div>\n                                <div class=\"cell shrink\">\n                                    <div class=\"title theme-text-color-primary\">Transcrire soi-m\u00eame<\/div>\n                                    <\/div>\n                                \n                                <div class=\"cell large-10 text-center\">\n                                    <p>Vous pouvez transcrire votre fichier audio en texte manuellement, \u00e0 l&rsquo;aide d&rsquo;un traitement de texte. Cependant, il faut savoir que la transcription d&rsquo;un fichier audio d&rsquo;une heure peut prendre jusqu&rsquo;\u00e0 6 heures !<\/p>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"carousel-cell usp-item\">\n                        <div class=\"grid-container\">\n                            <div class=\"grid-x align-center align-middle grid-margin-y grid-margin-x\">\n                                <div class=\"cell shrink\">\n                                <div class=\"usp-icon theme-background-secondary \">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2021\/07\/automatic-transcription-icon.png\" alt=\"Automatic transcription icon\">\n                                                                            <\/div>\n                                <\/div>\n                                <div class=\"cell shrink\">\n                                    <div class=\"title theme-text-color-primary\">Transcription automatique de fichiers audio en texte<\/div>\n                                    <\/div>\n                                \n                                <div class=\"cell large-10 text-center\">\n                                    <p>Notre convertisseur audio vers un texte cr\u00e9e automatiquement un premier document et fournit un \u00e9diteur de texte intuitif permettant d&rsquo;am\u00e9liorer le texte soi-m\u00eame. <\/p>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"carousel-cell usp-item\">\n                        <div class=\"grid-container\">\n                            <div class=\"grid-x align-center align-middle grid-margin-y grid-margin-x\">\n                                <div class=\"cell shrink\">\n                                <div class=\"usp-icon theme-background-secondary \">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2021\/07\/manual-transcription-icon.png\" alt=\"Manual transcription service icon\">\n                                                                            <\/div>\n                                <\/div>\n                                <div class=\"cell shrink\">\n                                    <div class=\"title theme-text-color-primary\">Obtenir une transcription de fichiers audio fait par des professionnels <\/div>\n                                    <\/div>\n                                \n                                <div class=\"cell large-10 text-center\">\n                                    <p>Nos transcripteurs professionnels convertissent vos documents audio en texte avec une pr\u00e9cision totale. L&rsquo;\u00e9quipe s&rsquo;appuie sur la technologie pour rendre le processus aussi facile, rapide et abordable que possible. <\/p>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n\n\n\t\t\n\n<section class=\"block tab-holder-steps\">\n    <div class=\"grid-container\">\n        <div class=\"grid-x grid-margin-x grid-margin-y\">\n            <div class=\"cell medium-12 text-center\">\n                            <\/div>\n            <div class=\"cell medium-12 text-center\">\n                \n                <div class=\"tab-holder-image\">\n\n\n                                                        \n                        <div class=\"tab-image is-active\" data-tab-image=\"0\">\n                            <img decoding=\"async\" width=\"573\" height=\"297\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2022\/10\/Screenshot-2022-04-26-at-17.01-2.png\" class=\"attachment-full size-full\" alt=\"Upload your audio or video file on our user-friendly platform in just a few seconds\" \/>\n                                                            <summary>\n                                    <p class=\"small\">T\u00e9l\u00e9chargez votre fichier audio ou vid\u00e9o sur notre plateforme facile d&#039;utilisation en quelques secondes seulement<\/p>\n                                <\/summary>\n                            \n                        <\/div>\n                \n\n                                        \n                        <div class=\"tab-image \" data-tab-image=\"1\">\n                            <img decoding=\"async\" width=\"640\" height=\"379\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2022\/08\/Video-Editor-compressed.png\" class=\"attachment-full size-full\" alt=\"ACC to text converter\" \/>\n                                                            <summary>\n                                    <p class=\"small\">T\u00e9l\u00e9chargez votre fichier audio ou vid\u00e9o sur notre plateforme facile d&#039;utilisation en quelques secondes seulement<\/p>\n                                <\/summary>\n                            \n                        <\/div>\n                \n\n                                        \n                        <div class=\"tab-image \" data-tab-image=\"2\">\n                            <img decoding=\"async\" width=\"1200\" height=\"628\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2022\/07\/transcription-app-header.jpg\" class=\"attachment-full size-full\" alt=\"Donna con in mano un telefono che usa l&#039;app di Amberscript\" srcset=\"https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2022\/07\/transcription-app-header.jpg 1200w, https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2022\/07\/transcription-app-header-640x335.jpg 640w, https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2022\/07\/transcription-app-header-768x402.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\n                                                            <summary>\n                                    <p class=\"small\">T\u00e9l\u00e9chargez votre fichier audio ou vid\u00e9o sur notre plateforme facile d&#039;utilisation en quelques secondes seulement<\/p>\n                                <\/summary>\n                            \n                        <\/div>\n                \n\n                                    \n\n                    <div class=\"tab-item\">\n                        <ul>\n\n                                                                                \n                                <li class=\"is-active\" data-tab-item=\"0\">\n                                    \n                                                                                <span>1<\/span> T\u00e9l\u00e9chargez                                                \n        \n                                                                            <\/li>\n\n                                                        \n                                <li class=\"\" data-tab-item=\"1\">\n                                    \n                                                                                <span>2<\/span> Choisissez votre service                                                \n        \n                                                                                    <div class=\"step-items\">\r\n    <div class=\"step-item\">\r\n        <span class=\"icon pencil\"><\/span>Professionnel\r\n    <\/div>\r\n    <div class=\"step-item\">\r\n        <span class=\"icon wheel\"><\/span>Automatique\r\n    <\/div>\r\n<\/div>\r\n                                                                            <\/li>\n\n                                                        \n                                <li class=\"\" data-tab-item=\"2\">\n                                    \n                                                                                <span>3<\/span> Exportez ou partagez                                                \n        \n                                                                            <\/li>\n\n                                                    \n                        <\/ul>\n                    <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"cell medium-12 text-center\">\n                                    <a class=\"button btn secondary\" href=\"https:\/\/app.amberscript.com\/register?lang=fr\" target=\"_self\" rel=\"noopener\">Commencez maintenant<\/a>\n                            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n\n<div class=\"block text-image\">\n\t<div class=\"grid-container\">\n      <div class=\"grid-x align-middle grid-margin-y grid-margin-x\">\n\t\t  \n\n        <div class=\"cell medium-6 large-5 medium-order-2 medium-offset-0 large-offset-1\t\">\t\t  \n\n                            <div class=\"image-holder text-center\">\n\n                                    <img decoding=\"async\" width=\"640\" height=\"352\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2022\/04\/amberscript-file-upload-640x352-compressed-8KB-1.png\" class=\"img-responsive\" alt=\"\" \/>                                    <\/div>\n            \t\t\t\n        <\/div>\n\t\t  \n\n        <div class=\"cell medium-6 large-5  \">  \n\n               \n                                                  \n                                                           <h3>1. Chargez vos fichiers audio<\/h3>\n                                    \n                                   <p>Cr\u00e9ez un compte gratuit et t\u00e9l\u00e9chargez votre fichier audio sur Amberscript, qui fait office de convertisseur audio\/texte. S\u00e9lectionnez la langue de l&rsquo;audio et le nombre de locuteurs pr\u00e9sents. Notre convertisseur audio en texte reconna\u00eet la parole dans 39 langues, et prend en charge plusieurs formats de fichiers comme MP3, AAC, WAV.<\/p>\n               \n                            \n        <\/div>\n      <\/div>\n   <\/div>\n<\/div>\n\n\n<div class=\"block text-image\">\n\t<div class=\"grid-container\">\n      <div class=\"grid-x align-middle grid-margin-y grid-margin-x\">\n\t\t  \n\n        <div class=\"cell medium-6 large-5 \t\">\t\t  \n\n                            <div class=\"image-holder text-center\">\n\n                                    <img decoding=\"async\" width=\"640\" height=\"393\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2021\/05\/Screen-8-640x393.png\" class=\"img-responsive\" alt=\"Mockup\" srcset=\"https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2021\/05\/Screen-8-640x393.png 640w, https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2021\/05\/Screen-8-1172x720.png 1172w, https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2021\/05\/Screen-8-768x472.png 768w, https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2021\/05\/Screen-8.png 1315w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>                                    <\/div>\n            \t\t\t\n        <\/div>\n\t\t  \n\n        <div class=\"cell medium-6 large-5  medium-offset-0 large-offset-1\">  \n\n               \n                                                  \n                                                           <h3>2. Modifiez vous-m\u00eame le texte <\/h3>\n                                    \n                                   <p>Le logiciel de reconnaissance automatique de la parole (RAP) \u00e9coute le fichier audio et le convertit en texte. Selon la qualit\u00e9 audio du fichier, la pr\u00e9cision peut atteindre 85 %. Vous pouvez ensuite perfectionner le texte vous-m\u00eame \u00e0 l&rsquo;aide de l&rsquo;\u00e9diteur en ligne facile \u00e0 utiliser. Mieux encore, vous pouvez mettre en \u00e9vidence les parties les plus importantes, renommer vos intervenants et ajuster les horodatages. C&rsquo;est 5 \u00e0 10 fois plus rapide que d&rsquo;\u00e9couter l&rsquo;audio et de taper le texte vous-m\u00eame.<\/p>\n               \n                                <a class=\"button theme-color-secondary\" id=\"button_block_d0215c903598dd3c02da6be0811106fd\" href=\"https:\/\/app.amberscript.com\/register?lang=fr\" target=\"_self\" rel=\"noopener\">Commencez maintenant<\/a>\n                            \n        <\/div>\n      <\/div>\n   <\/div>\n<\/div>\n\n\n<div class=\"block text-image\">\n\t<div class=\"grid-container\">\n      <div class=\"grid-x align-middle grid-margin-y grid-margin-x\">\n\t\t  \n\n        <div class=\"cell medium-6 large-5 \t\">\t\t  \n\n                            <div class=\"image-holder text-center\">\n\n                                    <img decoding=\"async\" width=\"640\" height=\"398\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2021\/06\/export-text-640x398.png\" class=\"img-responsive\" alt=\"Audio transcription online editor export options view\" srcset=\"https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2021\/06\/export-text-640x398.png 640w, https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2021\/06\/export-text-1158x720.png 1158w, https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2021\/06\/export-text-768x478.png 768w, https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2021\/06\/export-text-1536x955.png 1536w, https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2021\/06\/export-text-2048x1274.png 2048w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>                                    <\/div>\n            \t\t\t\n        <\/div>\n\t\t  \n\n        <div class=\"cell medium-6 large-5  medium-offset-0 large-offset-1\">  \n\n               \n                                                  \n                                                           <h3>3. Exportez votre fichier audio\/vid\u00e9o vers votre format de texte pr\u00e9f\u00e9r\u00e9.<\/h3>\n                                    \n                                   <p>Nous prenons en charge plusieurs formats de texte dans lesquels vous pouvez exporter et t\u00e9l\u00e9charger votre fichier :<\/p>\n<ul>\n<li><span data-sheets-value=\"{\" data-sheets-userformat=\"{\">.docx \u2013 Microsoft Word file format<\/span><\/li>\n<li><span data-sheets-value=\"{\" data-sheets-userformat=\"{\">.json \u2013 JavaScript Object Notation<\/span><\/li>\n<li><span data-sheets-value=\"{\" data-sheets-userformat=\"{\">.srt \u2013 SubRip Subtitle file<\/span><\/li>\n<li><span data-sheets-value=\"{\" data-sheets-userformat=\"{\">.vtt \u2013 Web Video Text Tracks<\/span><\/li>\n<li><span data-sheets-value=\"{\" data-sheets-userformat=\"{\">EBU-STL \u2013 European Broadcast Union subtitles<\/span><\/li>\n<li><span data-sheets-value=\"{\" data-sheets-userformat=\"{\">.txt \u2013 Plain text file<\/span><\/li>\n<\/ul>\n               \n                            \n        <\/div>\n      <\/div>\n   <\/div>\n<\/div>\n\n\n<div class=\"block languages \">\n        <div class=\"grid-container\">\n\n  <div class=\"grid-x grid-margin-y grid-margin-y align-center\">\n            <div class=\"cell large-12 text-center\">\n\t\t\t\t\n               \t\t\t\t\t\t\t\t\t\t\t\t<h2>39 langues<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n            <\/div>\n            <div class=\"cell large-6 text-center\">\n\t\t\t\t                <div class=\"grid-x grid-margin-y\">\n \n                      \t                                                         <div class=\"cell small-6 medium-4 large-4  \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/gb.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/gb.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"gb\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">ANG (tous les accents)<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4  \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/au.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/au.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"au\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Anglais (Australie)<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4  \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/gb.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/gb.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"gb\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Anglais (UK)<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4  \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/us.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/us.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"us\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Anglais (USA)<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4  \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/ca.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/ca.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"ca\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Anglais (Canada)<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4  \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/dk.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/dk.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"dk\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Danois<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4  \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/nl.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/nl.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"nl\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">N\u00e9erlandais<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4  \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/fi.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/fi.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"fi\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Finnois<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4  \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/fr.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/fr.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"fr\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Fran\u00e7ais<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/it.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/it.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"it\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Italien<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/de.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/de.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"de\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Allemand<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/no.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/no.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"no\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Norv\u00e9gien<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/pt.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/pt.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"pt\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Portugais<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/es.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/es.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"es\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Espagnol<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/se.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/se.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"se\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Su\u00e9dois<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/sa.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/sa.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"sa\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Arabe (Arabie Saoudite)<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/id.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/id.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"id\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Indon\u00e9sien<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/bd.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/bd.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"bd\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Bengali (Bangladesh)<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/in.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/in.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"in\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\"> Bengali (Inde)<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/bg.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/bg.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"bg\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Bulgare<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/es.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/es.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"es\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Catalan<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/cn.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/cn.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"cn\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Chinois mandarin<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/ir.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/ir.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"ir\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Farsi (Iran)<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/es.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/es.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"es\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Galicien<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/il.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/il.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"il\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">H\u00e9breu<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/gr.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/gr.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"gr\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Grec<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/in.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/in.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"in\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Hindi<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/hu.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/hu.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"hu\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Hongrois<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/jp.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/jp.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"jp\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Japonais<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/kr.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/kr.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"kr\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Cor\u00e9en<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/lt.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/lt.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"lt\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Lituanien<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/np.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/np.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"np\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">N\u00e9palais<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/pl.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/pl.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"pl\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Polonais<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/ro.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/ro.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"ro\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Roumain<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/ru.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/ru.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"ru\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Russe<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/tr.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/tr.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"tr\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Turc<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/ua.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/ua.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"ua\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Ukrainien<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/in.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/in.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"in\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Urdu (Inde)<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                        <div class=\"cell small-6 medium-4 large-4 all-languages \">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <div class=\"grid-x align-middle grid-margin-x\">\n                                    <div class=\"cell shrink\" style=\"margin-top: -4px\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\"\n\t\t\t\t\t\t\t\t\t\t  src=\"https:\/\/flagcdn.com\/w40\/pk.png\"\n\t\t\t\t\t\t\t\t\t\t  srcset=\"https:\/\/flagcdn.com\/w80\/pk.png 2x\"\n\t\t\t\t\t\t\t\t\t\t  width=\"40\"\n\t\t\t\t\t\t\t\t\t\t  alt=\"pk\" class=\"\" style=\"width: 21px\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n                                                                        <\/div>\n                                    <div class=\"cell shrink\">\n                                        <p class=\"nbm\">Urdu (Pakistan)<\/p>\n                                    <\/div>\n                                <\/div>\n\t\t                            <\/div>\n\n\n                                                    \n                    <\/div>\n                <\/div>\n\t       <div class=\"cell large-12 text-center language-btn-group\">\n                <div class=\"grid-x grid-margin-x grid-margin-y align-center\">\n                    <div class=\"cell shrink\">\n\t\t\t\t\t\t<div class=\"button primary language-toggle\">Montrez toutes les langues<\/div>\n                    <\/div>\n                    <div class=\"cell shrink\">\n                                                <a class=\"button secondary\" href=\"https:\/\/app.amberscript.com\/register?lang=fr\" target=\"_self\" rel=\"noopener\">Commencez maintenant<\/a>\n                                            <\/div>\n                <\/div>\n            <\/div>\n            <\/div>\n\t\t<\/div>\n<\/div>\n\n\n<div class=\"block accordion\">\n\t<div class=\"grid-container\" itemscope itemtype=\"https:\/\/schema.org\/FAQPage\">\n        <div class=\"grid-x align-center grid-margin-x grid-margin-y\">\n            \n<div class=\"cell large-12 text-center\">\n  <div class=\"title-holder\">\n\n\n\n                          <h6><span id=\"quels-sont-les-fichiers-audio-qui-peuvent-etre-convertis-en-texte\"><\/span><\/h6>\n                    \n                                    <h2>Quels sont les fichiers audio qui peuvent \u00eatre convertis en texte ?<\/h2>\n                      <\/div>           \n<\/div>\n\n            \n            <div class=\"cell medium-10 large-5 \">\n                            <\/div>\n            <div class=\"cell medium-10 large-5 large-offset-1\">\n                            <\/div>\n\n        \n            \n            \n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n\n<div class=\"block text-image\">\n\t<div class=\"grid-container\">\n      <div class=\"grid-x align-middle grid-margin-y grid-margin-x\">\n\t\t  \n\n        <div class=\"cell medium-6 large-5 \t\">\t\t  \n\n                            <div class=\"image-holder text-center\">\n\n                                    <img decoding=\"async\" width=\"640\" height=\"361\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2023\/05\/Transcription-service-6-640x361.png\" class=\"img-responsive\" alt=\"\" srcset=\"https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2023\/05\/Transcription-service-6-640x361.png 640w, https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2023\/05\/Transcription-service-6-1278x720.png 1278w, https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2023\/05\/Transcription-service-6-768x433.png 768w, https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2023\/05\/Transcription-service-6-1536x865.png 1536w, https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2023\/05\/Transcription-service-6.png 1640w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>                                    <\/div>\n            \t\t\t\n        <\/div>\n\t\t  \n\n        <div class=\"cell medium-6 large-5  medium-offset-0 large-offset-1\">  \n\n               \n                \n                           \n               \n                                                  \n                                   <p>Les fichiers audio peuvent \u00eatre convertis en texte \u00e0 l&rsquo;aide de diff\u00e9rentes m\u00e9thodes, notamment les logiciels de transcription automatique et la transcription manuelle. Les formats de fichiers audio les plus courants qui peuvent \u00eatre convertis en texte sont les suivants : <em><strong>MP3, AAC, DSS, WAV, M4A<\/strong><\/em> et <em><strong>FLAC<\/strong><\/em>. Ces formats de fichiers sont largement pris en charge par la plupart des logiciels de transcription, ce qui en fait le choix id\u00e9al pour la conversion de fichiers audio en texte. La conversion de fichiers audio en texte est un outil pr\u00e9cieux pour de nombreux secteurs, notamment les m\u00e9dias, le marketing et l&rsquo;\u00e9ducation, car elle permet d&rsquo;obtenir une trace \u00e9crite pr\u00e9cise et accessible des propos tenus.<\/p>\n               \n                            \n        <\/div>\n      <\/div>\n   <\/div>\n<\/div>\n\n\n<div class=\"block accordion\">\n\t<div class=\"grid-container\" itemscope itemtype=\"https:\/\/schema.org\/FAQPage\">\n        <div class=\"grid-x align-center grid-margin-x grid-margin-y\">\n            \n<div class=\"cell large-12 text-center\">\n  <div class=\"title-holder\">\n\n\n\n                    \n                                    <h2>Formats de fichiers audio<\/h2>\n                      <\/div>           \n<\/div>\n\n            \n            <div class=\"cell medium-10 large-5 \">\n                                    <ul class=\"accordion\" data-accordion  data-allow-all-closed=\"true\">\n                                            <li class=\"accordion-item\" data-accordion-item itemscope itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\">\n                            <a href=\"#\" class=\"accordion-title\">\n\t\t\t\t\t\t\t\t<div itemprop=\"name\">\n                            \t\tAAC\t\t\t\t\t\t\t\t<\/div>\n                            <\/a>\n                            <div class=\"accordion-content\" data-tab-content itemscope itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\">\n\t\t\t\t\t\t\t\t<div itemprop=\"text\">\n\t\t                            <p><strong>Advanced Audio Coding<\/strong> est un format de compression audio num\u00e9rique avec perte, que vous pouvez charger dans le convertisseur audio en texte. \u00c0 l&rsquo;origine, ce format de fichier \u00e9tait cens\u00e9 remplacer le format MP3, car il offre une qualit\u00e9 sonore sup\u00e9rieure pour un d\u00e9bit binaire identique. <a href=\"https:\/\/wp-staging.amberscript.com\/fr\/aac-en-texte\/\">En savoir plus sur la fa\u00e7on de convertir AAC en texte.<\/a><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n                            <\/div>\n                        <\/li>\n                                            <li class=\"accordion-item\" data-accordion-item itemscope itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\">\n                            <a href=\"#\" class=\"accordion-title\">\n\t\t\t\t\t\t\t\t<div itemprop=\"name\">\n                            \t\tDSS\t\t\t\t\t\t\t\t<\/div>\n                            <\/a>\n                            <div class=\"accordion-content\" data-tab-content itemscope itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\">\n\t\t\t\t\t\t\t\t<div itemprop=\"text\">\n\t\t                            <p>Un fichier .dss<strong> (Digital Speech Standard)<\/strong>\u00a0 d\u00e9velopp\u00e9 en 1994 pour stocker des donn\u00e9es audio vocales dans un format hautement compress\u00e9. Utilis\u00e9 principalement pour les enregistreurs de dict\u00e9e num\u00e9rique, gr\u00e2ce \u00e0 une fonctionnalit\u00e9 d&rsquo;enregistrement de base et \u00e0 la possibilit\u00e9 de passer en mode d&rsquo;\u00e9crasement.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n                            <\/div>\n                        <\/li>\n                                            <li class=\"accordion-item\" data-accordion-item itemscope itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\">\n                            <a href=\"#\" class=\"accordion-title\">\n\t\t\t\t\t\t\t\t<div itemprop=\"name\">\n                            \t\tFLAC\t\t\t\t\t\t\t\t<\/div>\n                            <\/a>\n                            <div class=\"accordion-content\" data-tab-content itemscope itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\">\n\t\t\t\t\t\t\t\t<div itemprop=\"text\">\n\t\t                            <p>Le Flac ou\u00a0<strong>Free Lossless Audio Codec<\/strong>\u00a0est un format audio\u00a0<span class=\"link-wrapper\">open source.<\/span> Les fichiers compress\u00e9s \u00e0 l&rsquo;aide de ce format peuvent \u00eatre r\u00e9duits de 50 \u00e0 70 % de leur taille d&rsquo;origine et contiennent une copie identique des donn\u00e9es audio d&rsquo;origine. Pour en savoir plus sur la conversion de FLAC en texte, <a href=\"https:\/\/wp-staging.amberscript.com\/fr\/flac-en-texte\/\">cliquez ici<\/a>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n                            <\/div>\n                        <\/li>\n                                        <\/ul>\n                            <\/div>\n            <div class=\"cell medium-10 large-5 large-offset-1\">\n                                <ul class=\"accordion\" data-accordion  data-allow-all-closed=\"true\">\n                                    <li class=\"accordion-item\" data-accordion-item itemscope itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\">\n                        <a href=\"#\" class=\"accordion-title\">\n\t\t\t\t\t\t\t<div itemprop=\"name\">\n                            M4A\t\t\t\t\t\t\t<\/div>\n                        <\/a>\n                        <div class=\"accordion-content\" data-tab-content itemscope itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\">\n\t\t\t\t\t\t      <div itemprop=\"text\">\n\t\t                        <p>Un fichier avec l&rsquo;extension de fichier M4A est un fichier audio <strong>MPEG-4<\/strong>. Il est le plus souvent utilis\u00e9 pour les contenus audio tels que les chansons, les podcasts ou les livres audio. <a href=\"https:\/\/wp-staging.amberscript.com\/fr\/m4a-en-texte\/\">Convertissez le fichier M4A en texte.<\/a><\/p>\n\t\t\t\t\t\t\t<\/div>\n                        <\/div>\n                    <\/li>\n                                    <li class=\"accordion-item\" data-accordion-item itemscope itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\">\n                        <a href=\"#\" class=\"accordion-title\">\n\t\t\t\t\t\t\t<div itemprop=\"name\">\n                            MP3\t\t\t\t\t\t\t<\/div>\n                        <\/a>\n                        <div class=\"accordion-content\" data-tab-content itemscope itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\">\n\t\t\t\t\t\t      <div itemprop=\"text\">\n\t\t                        <p>Le\u00a0<b>MPEG-1\/2 Audio Layer III <\/b>est plus connu sous son abr\u00e9viation de <b>MP3. <\/b>Il utilise une compression des donn\u00e9es avec perte. Cela permet une r\u00e9duction significative de la taille du fichier par rapport \u00e0 la source audio. Vous trouverez plus d&rsquo;informations sur la <a href=\"https:\/\/wp-staging.amberscript.com\/fr\/mp3-en-texte\/\">conversion de MP3 en texte ici.<\/a><\/p>\n\t\t\t\t\t\t\t<\/div>\n                        <\/div>\n                    <\/li>\n                                    <li class=\"accordion-item\" data-accordion-item itemscope itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\">\n                        <a href=\"#\" class=\"accordion-title\">\n\t\t\t\t\t\t\t<div itemprop=\"name\">\n                            WAV\t\t\t\t\t\t\t<\/div>\n                        <\/a>\n                        <div class=\"accordion-content\" data-tab-content itemscope itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\">\n\t\t\t\t\t\t      <div itemprop=\"text\">\n\t\t                        <section id=\"overview\" class=\"article_content\">\n<p class=\"first-paragraph\">Le <strong>format de fichier audio Waveform<\/strong> a \u00e9t\u00e9 d\u00e9velopp\u00e9 par IBM et Microsoft et \u00e9tait \u00e0 l&rsquo;origine utilis\u00e9 sur les syst\u00e8mes Microsoft Windows pour stocker des donn\u00e9es audio brutes et non compress\u00e9es. <a class=\"avia-button av-icon-on-hover avia-icon_select-no avia-color-custom avia-size-small avia-position-center \" href=\"https:\/\/wp-staging.amberscript.com\/fr\/wav-en-texte\/\"><span class=\"avia_iconbox_title\">Convertissez votre WAV en Texte<\/span><\/a><\/p>\n<\/section>\n<section id=\"section_G\u00e9n\u00e9ralit\u00e9s\" class=\"article_content\"><\/section>\n\t\t\t\t\t\t\t<\/div>\n                        <\/div>\n                    <\/li>\n                                <\/ul>\n                        <\/div>\n\n        \n            \n            \n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n\n<section class=\"block product-cards\">\n    <div class=\"grid-container\">\n        <div class=\"grid-x grid-margin-x grid-margin-y\" data-equalizer data-equalize-on-stack=\"true\">\n\n                            \n                        <div class=\"cell medium-12 large-6\">\n                            <article class=\"card product\n                                                        green-orange\n                                                        \" >\n                                <div class=\"header\">\n                                    <div class=\"shape \n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t ntm                                     orange show-for-large\n                                    \"><\/div>\n\n                                    \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<!-- The style makes sure we indent on the right side for 22%, to not overflow the yellow image -->\n                                        <h2 style=\"direction: rtl; text-align: left; text-indent: 22%;\"\n\t\t\t\t\t\t\t\t\t\t\t class=\"h3\"  \t\t\t\t\t\t\t\t\t\t\t>Transcriptions automatiques<\/h2>\n                                                                        \n                                                                            <p>L&#039;intelligence artificielle (IA) cr\u00e9e une \u00e9bauche de votre transcription dans la langue de l&#039;audio.<\/p>\n                                                                    <\/div>\n                                    <div class=\"inner\">\n                                        <div class=\"grid-x grid-margin-x grid-margin-y align-center\">\n                                            <div class=\"cell small-12 text-center\">\n                                                <figure>\n                                                    <img decoding=\"async\" width=\"1280\" height=\"604\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2022\/04\/automatic-transcription.svg\" class=\"shape\" alt=\"\" \/>                                                <\/figure>\n                                            <\/div>\n                                    \n                                        <\/div>\n\n                                    <div data-equalizer-watch class=\"text-holder\">\n                                                                                    <ul class=\"checked\">\n<li><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Transcription audio compl\u00e8te en quelques minutes&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:769,&quot;3&quot;:{&quot;1&quot;:0},&quot;11&quot;:4,&quot;12&quot;:0}\">Transcription audio compl\u00e8te en quelques minutes<\/span><\/li>\n<li><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Solution rentable pour les petits projets&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:769,&quot;3&quot;:{&quot;1&quot;:0},&quot;11&quot;:4,&quot;12&quot;:0}\">Solution rentable pour les petits projets<\/span><\/li>\n<li><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u00c9diteur en ligne transparent pour modifier vos transcriptions&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:769,&quot;3&quot;:{&quot;1&quot;:0},&quot;11&quot;:4,&quot;12&quot;:0}\">\u00c9diteur en ligne transparent pour modifier vos transcriptions<\/span><\/li>\n<\/ul>\n                                        \t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \n                                        <div class=\"grid-x grid-margin-x grid-margin-y info sbm\">\n\n                                                                                            <div class=\"cell auto medium-shrink\">\n                                                    <div class=\"service-info\">\n                                                        Jusqu&rsquo;\u00e0<br \/><span class=\"number\">85%<\/span><br \/>de pr\u00e9cision                                                    <\/div>\n                                                <\/div>\n                                                                                        \t\t\t\t\t\t\t\t\t\t\t  <div class=\"cell auto medium-shrink\">\n                                                <div class=\"service-info\">\n                                                                                                            \u00c0 partir de<br \/>                                                                                                        <span class=\"number\">\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                                            US$                                                                                                             <\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t                                                            <div class=\"service-info\">\n                                                            par minute                                                        <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n\t\t\t\t\t\t\t\t\t\t\t                                          \n\n\n                                                                                            <div class=\"cell auto medium-shrink\">\n                                                    D\u00e9lai d&rsquo;ex\u00e9cution de seulement<br \/><span class=\"number\">5 minutes<\/span><br \/>                                                <\/div>\n                                            \n                                        <\/div>\n\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t\t\t\n\n\n\n                                    <div class=\"grid-x grid-margin-x grid-margin-y\">\n\n                                                                                    <div class=\"cell medium-shrink\">\n                                                <a class=\"button btn orange\" href=\"https:\/\/app.amberscript.com\/register?lang=fr\" target=\"_self\" rel=\"noopener\">Obtenez des minutes gratuites <\/a>\n                                            <\/div>\n                                            \n                                        \n                                                                                    <div class=\"cell medium-shrink\">\n                                                <a class=\"button btn orange-invert\" href=\"https:\/\/wp-staging.amberscript.com\/fr\/produits\/transcription-automatique\/\" target=\"_self\">En savoir plus<\/a>\n                                            <\/div>\n                                                                                \n                                        \n                                    <\/div>\n                                <\/div>\n                            <\/article>\n                        <\/div>\n                \n\n                \n                        <div class=\"cell medium-12 large-6\">\n                            <article class=\"card product\n                                                        green-orange\n                                                        \" >\n                                <div class=\"header\">\n                                    <div class=\"shape \n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t ntm                                     orange show-for-large\n                                    \"><\/div>\n\n                                    \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<!-- The style makes sure we indent on the right side for 22%, to not overflow the yellow image -->\n                                        <h2 style=\"direction: rtl; text-align: left; text-indent: 22%;\"\n\t\t\t\t\t\t\t\t\t\t\t class=\"h3\"  \t\t\t\t\t\t\t\t\t\t\t>Transcriptions Professionnelles <\/h2>\n                                                                        \n                                                                            <p>Notre \u00e9quipe de professionnels cr\u00e9e des transcriptions 100% exactes, afin que vous puissiez vous concentrer sur les projets qui vous tiennent vraiment \u00e0 c\u0153ur.<\/p>\n                                                                    <\/div>\n                                    <div class=\"inner\">\n                                        <div class=\"grid-x grid-margin-x grid-margin-y align-center\">\n                                            <div class=\"cell small-12 text-center\">\n                                                <figure>\n                                                    <img decoding=\"async\" width=\"1280\" height=\"646\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2022\/04\/Human-transcript.svg\" class=\"shape\" alt=\"\" \/>                                                <\/figure>\n                                            <\/div>\n                                    \n                                        <\/div>\n\n                                    <div data-equalizer-watch class=\"text-holder\">\n                                                                                    <ul class=\"checked\">\n<li><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Un texte fiable auquel vous pouvez faire confiance&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:769,&quot;3&quot;:{&quot;1&quot;:0},&quot;11&quot;:4,&quot;12&quot;:0}\">Un texte fiable auquel vous pouvez faire confiance<\/span><\/li>\n<li><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Sans effort, nous nous occupons de tout de A \u00e0 Z&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:769,&quot;3&quot;:{&quot;1&quot;:0},&quot;11&quot;:4,&quot;12&quot;:0}\">Sans effort, nous nous occupons de tout de A \u00e0 Z<\/span><\/li>\n<li><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Livraison rapide, quel que soit le volume de votre contenu&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:769,&quot;3&quot;:{&quot;1&quot;:0},&quot;11&quot;:4,&quot;12&quot;:0}\">Livraison rapide, quel que soit le volume de votre contenu<\/span><\/li>\n<\/ul>\n                                        \t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \n                                        <div class=\"grid-x grid-margin-x grid-margin-y info sbm\">\n\n                                                                                            <div class=\"cell auto medium-shrink\">\n                                                    <div class=\"service-info\">\n                                                        Toujours<br \/><span class=\"number\">100%<\/span><br \/>de pr\u00e9cision                                                    <\/div>\n                                                <\/div>\n                                                                                        \t\t\t\t\t\t\t\t\t\t\t  <div class=\"cell auto medium-shrink\">\n                                                <div class=\"service-info\">\n                                                                                                            \u00c0 partir de <br \/>                                                                                                        <span class=\"number\">\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                                            US$                                                                                                             <\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t                                                            <div class=\"service-info\">\n                                                            par minute                                                        <\/div>\n                                                                                                    <\/div>\n                                            <\/div>\n\t\t\t\t\t\t\t\t\t\t\t                                          \n\n\n                                                                                            <div class=\"cell auto medium-shrink\">\n                                                    D\u00e9lai d&rsquo;ex\u00e9cution de<br \/><span class=\"number\">24h<\/span><br \/> seulement                                                <\/div>\n                                            \n                                        <\/div>\n\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t\t\t\n\n\n\n                                    <div class=\"grid-x grid-margin-x grid-margin-y\">\n\n                                                                                    <div class=\"cell medium-shrink\">\n                                                <a class=\"button btn orange\" href=\"https:\/\/app.amberscript.com\/register?lang=fr\" target=\"_self\" rel=\"noopener\">Demander un devis<\/a>\n                                            <\/div>\n                                            \n                                        \n                                                                                    <div class=\"cell medium-shrink\">\n                                                <a class=\"button btn orange-invert\" href=\"https:\/\/wp-staging.amberscript.com\/fr\/produits\/transcription-manuelle\/\" target=\"_self\">En savoir plus<\/a>\n                                            <\/div>\n                                                                                \n                                        \n                                    <\/div>\n                                <\/div>\n                            <\/article>\n                        <\/div>\n                \n\n                            \n\n        <\/div>\n    <\/div>\n<\/section>\n\n\n\n<div class=\"block accordion\">\n\t<div class=\"grid-container\" itemscope itemtype=\"https:\/\/schema.org\/FAQPage\">\n        <div class=\"grid-x align-center grid-margin-x grid-margin-y\">\n            \n<div class=\"cell large-12 text-center\">\n  <div class=\"title-holder\">\n\n\n\n                          <h6><span id=\"avantages-et-inconvenients-des-formats-mp3-flac-et-aac\"><\/span><\/h6>\n                    \n                                    <h2>Avantages et inconv\u00e9nients des formats MP3, FLAC et AAC<\/h2>\n                      <\/div>           \n<\/div>\n\n            \n            <div class=\"cell medium-10 large-5 \">\n                            <\/div>\n            <div class=\"cell medium-10 large-5 large-offset-1\">\n                            <\/div>\n\n        \n            \n            \n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n\n<style>\n\t.card-image{\n\t\twidth: 100%;\n\t\theight: 200px;\n\t\tobject-fit: contain;\n\t\tmargin-bottom: 2rem;\n\t}\n<\/style>\n\n<div class=\"block button-cards\">\n    <div class=\"grid-container\">\n        <div class=\"grid-x align-center grid-margin-x grid-margin-y\">\n            \n<div class=\"cell large-12 text-center\">\n  <div class=\"title-holder\">\n\n\n\n                          <h6>Avantages<\/h6>\n                    \n                              <\/div>           \n<\/div>\n                        \n                \n                <div class=\"cell medium-4 large-4\">\n                    <div class=\"background border-radius\">\n                        <div class=\"inner\">\n\t\t\t\t\t\t\t\n                            <h5>MP3<\/h5>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<p><em>Le format MP3 est un format audio largement utilis\u00e9 pour partager et lire de la musique sur divers appareils. Sa petite taille facilite le stockage et le partage de fichiers audio sur internet. De plus, il offre une qualit\u00e9 sonore excellente et est pratique pour le partage en ligne.<\/em><\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n                            \t\t\t\t\t\t\t\n                            \t\t\t\t\t\t\t\n                        <\/div>\n                    <\/div>\n                <\/div>\n                    \n                \n                <div class=\"cell medium-4 large-4\">\n                    <div class=\"background border-radius\">\n                        <div class=\"inner\">\n\t\t\t\t\t\t\t\n                            <h5>FLAC<\/h5>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<p><em>FLAC est un format audio sans perte qui pr\u00e9serve chaque d\u00e9tail de l\u2019enregistrement original, ce qui le rend id\u00e9al pour les enregistrements audio haute fid\u00e9lit\u00e9. Cependant, la taille importante des fichiers peut rendre difficile leur stockage et leur partage.<\/em><\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n                            \t\t\t\t\t\t\t\n                            \t\t\t\t\t\t\t\n                        <\/div>\n                    <\/div>\n                <\/div>\n                    \n                \n                <div class=\"cell medium-4 large-4\">\n                    <div class=\"background border-radius\">\n                        <div class=\"inner\">\n\t\t\t\t\t\t\t\n                            <h5>AAC<\/h5>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<p>AAC est un format audio compress\u00e9 avec une meilleure qualit\u00e9 et une taille r\u00e9duite par rapport au MP3, il est id\u00e9al pour stocker et partager des enregistrements audio de haute qualit\u00e9 sur des appareils limit\u00e9s et diffuser du contenu audio en ligne.<\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n                            \t\t\t\t\t\t\t\n                            \t\t\t\t\t\t\t\n                        <\/div>\n                    <\/div>\n                <\/div>\n                    \n                            \n                        \n        <\/div>\n    <\/div>\n<\/div>\n\n<style>\n\t.card-image{\n\t\twidth: 100%;\n\t\theight: 200px;\n\t\tobject-fit: contain;\n\t\tmargin-bottom: 2rem;\n\t}\n<\/style>\n\n<div class=\"block button-cards\">\n    <div class=\"grid-container\">\n        <div class=\"grid-x align-center grid-margin-x grid-margin-y\">\n            \n<div class=\"cell large-12 text-center\">\n  <div class=\"title-holder\">\n\n\n\n                          <h6>Inconv\u00e9nients<\/h6>\n                    \n                                    <h2><span id=\"secteurs-beneficiant-des-convertisseurs-audio-texte\"><\/span><\/h2>\n                      <\/div>           \n<\/div>\n                        \n                \n                <div class=\"cell medium-4 large-4\">\n                    <div class=\"background border-radius\">\n                        <div class=\"inner\">\n\t\t\t\t\t\t\t\n                            <h5>MP3<\/h5>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<p><em>Le format MP3 est un format de compression avec perte qui sacrifie une partie de la qualit\u00e9 audio pour r\u00e9duire la taille du fichier. Cela peut entra\u00eener une perte de qualit\u00e9 audio, en particulier pour les enregistrements audio plus complexes.<\/em><\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n                            \t\t\t\t\t\t\t\n                            \t\t\t\t\t\t\t\n                        <\/div>\n                    <\/div>\n                <\/div>\n                    \n                \n                <div class=\"cell medium-4 large-4\">\n                    <div class=\"background border-radius\">\n                        <div class=\"inner\">\n\t\t\t\t\t\t\t\n                            <h5>FLAC<\/h5>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<p><em>FLAC offre une qualit\u00e9 sonore sup\u00e9rieure, mais les fichiers sont plus volumineux que les fichiers MP3, ce qui peut les rendre difficiles \u00e0 partager et \u00e0 stocker, et tous les appareils multim\u00e9dias ne prennent pas en charge ce format. Il en reste n\u00e9anmoins tr\u00e8s populaire.<\/em><\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n                            \t\t\t\t\t\t\t\n                            \t\t\t\t\t\t\t\n                        <\/div>\n                    <\/div>\n                <\/div>\n                    \n                \n                <div class=\"cell medium-4 large-4\">\n                    <div class=\"background border-radius\">\n                        <div class=\"inner\">\n\t\t\t\t\t\t\t\n                            <h5>AAC<\/h5>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<p><em>Tous les lecteurs et appareils multim\u00e9dias ne prennent pas en charge le format AAC, ce qui peut en limiter l&rsquo;accessibilit\u00e9. La lecture peut \u00e9galement n\u00e9cessiter un logiciel ou des appareils sp\u00e9cifiques, ce qui peut constituer un obstacle pour certains utilisateurs.<\/em><\/p>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n                            \t\t\t\t\t\t\t\n                            \t\t\t\t\t\t\t\n                        <\/div>\n                    <\/div>\n                <\/div>\n                    \n                            \n                        \n        <\/div>\n    <\/div>\n<\/div>\n\n<div class=\"block\">\n    <div class=\"grid-container \">\n        <div class=\"grid-x grid-margin-x grid-margin-y\">\n\n            \n            <div class=\"cell large-12 text-center\">\n                            <div class=\"title-holder\">                \n                    <h2>Les secteurs b\u00e9n\u00e9ficiant des convertisseurs audio\/texte<\/h2>\n                <\/div>           \n            <\/div>\n            \n                                                    <div class=\"cell small-12 medium-6\">\n                                                            <a href=\"https:\/\/wp-staging.amberscript.com\/fr\/demandez-un-devis\/\" target=\"_self\">\n                                                        <div class=\"icon-card aos-init aos-animate\">\n                                <div class=\"grid-x grid-margin-x align-middle\">\n                                                                                                      \n                                                                            <div class=\"cell auto\">\n                                            <div class=\"title\">Enseignement et recherche<\/div>\n                                        <\/div>\n                                                                                                                <div class=\"cell small-12\">\n                                            <p>Si vous \u00eates \u00e9tudiant et que vous aimez enregistrer vos cours, la transcription audio est faite pour vous. Cette m\u00e9thode de r\u00e9vision permet de pr\u00e9parer les \u00e9tudiants aux examens en revoyant les notes de cours. \r\n\r\n\r\n\r\nLes convertisseurs audio\/texte peuvent \u00e9galement aider \u00e0 sous-titrer les cours et les s\u00e9minaires en ligne et aider les \u00e9tudiants \u00e0 mieux suivre. <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                                                            <\/a>\n                                                    <\/div>\n\n                                        <div class=\"cell small-12 medium-6\">\n                                                            <a href=\"https:\/\/wp-staging.amberscript.com\/fr\/demandez-un-devis\/\" target=\"_self\">\n                                                        <div class=\"icon-card aos-init aos-animate\">\n                                <div class=\"grid-x grid-margin-x align-middle\">\n                                                                                    <div class=\"cell shrink medium-12 justify-center\">\n                                                <div class=\"usp-icon\">\n                                                    <img decoding=\"async\" width=\"20\" height=\"18\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2022\/10\/corporate_fare.svg\" class=\"attachment-full size-full\" alt=\"\" \/>                                                <\/div>\n                                            <\/div>\n                                                                                                          \n                                                                            <div class=\"cell auto\">\n                                            <div class=\"title\">Entreprises<\/div>\n                                        <\/div>\n                                                                                                                <div class=\"cell small-12\">\n                                            <p>Le monde professionnel est devenu plus t\u00e9l\u00e9connect\u00e9, ce qui accro\u00eet la demande de services de transcription d&rsquo;enregistrements audio en textes. Les entreprises produisant de plus en plus de contenu audio, il n&rsquo;est pas \u00e9tonnant qu&rsquo;elles soient de plus en plus nombreuses \u00e0 opter pour la transcription de leurs enregistrements. Apr\u00e8s tout, les transcriptions de conf\u00e9rences t\u00e9l\u00e9phoniques, d&rsquo;entretiens avec les RH, de r\u00e9unions en ligne ou de podcasts sont utiles \u00e0 toute entreprise.<\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                                                            <\/a>\n                                                    <\/div>\n\n                                        <div class=\"cell small-12 medium-6\">\n                                                            <a href=\"https:\/\/wp-staging.amberscript.com\/fr\/demandez-un-devis\/\" target=\"_self\">\n                                                        <div class=\"icon-card aos-init aos-animate\">\n                                <div class=\"grid-x grid-margin-x align-middle\">\n                                                                                    <div class=\"cell shrink medium-12 justify-center\">\n                                                <div class=\"usp-icon\">\n                                                    <img decoding=\"async\" width=\"24\" height=\"24\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2022\/10\/medical_information.svg\" class=\"attachment-full size-full\" alt=\"\" \/>                                                <\/div>\n                                            <\/div>\n                                                                                                          \n                                                                            <div class=\"cell auto\">\n                                            <div class=\"title\">Chercheurs<\/div>\n                                        <\/div>\n                                                                                                                <div class=\"cell small-12\">\n                                            <p>Lorsque vous documentez vos entretiens et r\u00e9unions, vous rendez les r\u00e9sultats de votre recherche plus accessibles. De plus, la transcription de tous les enregistrements permet de cr\u00e9er des documents textuels consultables qui sont plus faciles \u00e0 parcourir. Nos services de transcription pour la recherche universitaire sont abordables et vous font gagner du temps.<\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                                                            <\/a>\n                                                    <\/div>\n\n                                        <div class=\"cell small-12 medium-6\">\n                                                            <a href=\"https:\/\/wp-staging.amberscript.com\/fr\/demandez-un-devis\/\" target=\"_self\">\n                                                        <div class=\"icon-card aos-init aos-animate\">\n                                <div class=\"grid-x grid-margin-x align-middle\">\n                                                                                    <div class=\"cell shrink medium-12 justify-center\">\n                                                <div class=\"usp-icon\">\n                                                    <img decoding=\"async\" width=\"18\" height=\"19\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2022\/10\/gavel.svg\" class=\"attachment-full size-full\" alt=\"\" \/>                                                <\/div>\n                                            <\/div>\n                                                                                                          \n                                                                            <div class=\"cell auto\">\n                                            <div class=\"title\">Gouvernement<\/div>\n                                        <\/div>\n                                                                                                                <div class=\"cell small-12\">\n                                            <p>Les collectivit\u00e9s locales peuvent tirer parti de la transcription audio vers le texte pour stocker et consulter facilement les proc\u00e8s-verbaux des r\u00e9unions. Les municipalit\u00e9s peuvent \u00e9galement publier leurs transcriptions en ligne pour que leurs citoyens puissent les lire. <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                                                            <\/a>\n                                                    <\/div>\n\n                                        <div class=\"cell small-12 medium-6\">\n                                                            <a href=\"https:\/\/wp-staging.amberscript.com\/fr\/demandez-un-devis\/\" target=\"_self\">\n                                                        <div class=\"icon-card aos-init aos-animate\">\n                                <div class=\"grid-x grid-margin-x align-middle\">\n                                                                                    <div class=\"cell shrink medium-12 justify-center\">\n                                                <div class=\"usp-icon\">\n                                                    <img decoding=\"async\" width=\"24\" height=\"24\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2022\/10\/movie.svg\" class=\"attachment-full size-full\" alt=\"\" \/>                                                <\/div>\n                                            <\/div>\n                                                                                                          \n                                                                            <div class=\"cell auto\">\n                                            <div class=\"title\">M\u00e9dias et journalisme<\/div>\n                                        <\/div>\n                                                                                                                <div class=\"cell small-12\">\n                                            <p>Pour ajouter des sous-titres \u00e0 une vid\u00e9o, vous devez transcrire la parole dans un fichier texte. Vous pouvez utiliser un convertisseur audio\/texte pour acc\u00e9l\u00e9rer ce processus. Toutefois, si vous souhaitez cr\u00e9er des sous-titres rapidement et facilement, vous pouvez utiliser Amberscript. \r\n\r\n\r\n\r\nLes transcriptions aident \u00e9galement les producteurs \u00e0 reconstituer les vid\u00e9os en phase de post-production. Ce processus s&rsquo;appelle le rep\u00e9rage et il contribue \u00e0 rendre cette phase plus facile et plus rapide. <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                                                            <\/a>\n                                                    <\/div>\n\n                                        <div class=\"cell small-12 medium-6\">\n                                                            <a href=\"https:\/\/wp-staging.amberscript.com\/fr\/demandez-un-devis\/\" target=\"_self\">\n                                                        <div class=\"icon-card aos-init aos-animate\">\n                                <div class=\"grid-x grid-margin-x align-middle\">\n                                                                                    <div class=\"cell shrink medium-12 justify-center\">\n                                                <div class=\"usp-icon\">\n                                                    <img decoding=\"async\" width=\"24\" height=\"24\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/uploads\/2022\/10\/add_box.svg\" class=\"attachment-full size-full\" alt=\"\" \/>                                                <\/div>\n                                            <\/div>\n                                                                                                          \n                                                                            <div class=\"cell auto\">\n                                            <div class=\"title\">Podcasters<\/div>\n                                        <\/div>\n                                                                                                                <div class=\"cell small-12\">\n                                            <p>La conversion de l&rsquo;audio en texte a de nombreuses utilit\u00e9s, notamment celle de rendre le contenu plus accessible et d&rsquo;am\u00e9liorer la visibilit\u00e9 sur le plan du r\u00e9f\u00e9rencement. Pour les podcasters, la transcription de l&rsquo;audio et le t\u00e9l\u00e9chargement du texte sur un site web permettent d&rsquo;atteindre un public plus large et d&rsquo;aider les personnes sourdes ou malentendantes \u00e0 s&rsquo;int\u00e9resser au contenu. En outre, la conversion de l&rsquo;audio en texte permet de rendre le contenu plus accessible et d&rsquo;augmenter sa port\u00e9e.<\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                                                            <\/a>\n                                                    <\/div>\n\n                                    <\/div>\n    <\/div>\n    \n<\/div>\n\n\n<div class=\"block text-image\">\n    <div class=\"grid-container\">\n        <div class=\"grid-x grid-margin-x align-middle\">\n            <div class=\"cell medium-5 medium-offset-1 medium-order-2\">\n                <p><span id=\"comment-nous-convertissons-un-fichier-audio-en-texte\"><\/span><\/p>\n<h2>Comment nous convertissons un fichier audio en texte<\/h2>\n<p>Convertissez facilement et gratuitement votre fichier audio en texte avec Amberscript. Notre technologie intuitive de reconnaissance automatique de la parole (ASR) convertit vos fichiers audio en texte avec une grande pr\u00e9cision et une grande rapidit\u00e9.<\/p>\n<p>Modifiez les transcriptions vous-m\u00eame dans notre \u00e9diteur en ligne, ou commandez des services manuels, o\u00f9 nos professionnels se chargeront de la v\u00e9rification.<\/p>\n<p>Notre service est un v\u00e9ritable centre de transcription audio, o\u00f9 le processus de conversion des fichiers audio en texte est jusqu&rsquo;\u00e0 10 fois plus rapide.<\/p>\n                            <\/div>\n            <div class=\"cell medium-5\">\n\n\n                                    <div class=\"video-container\">\n                        <div class=\"video-holder video youtube\" data-embed=\"KZofqSc-k1s\">\n                            <div class=\"video-inner\"><\/div>\n                            <svg class=\"play-button\"\n                                width=\"120\"\n                                height=\"120\"\n                                viewBox=\"0 0 24 24\"\n                                fill=\"none\"\n                                xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n                                >\n                                <path d=\"M15 12.3301L9 16.6603L9 8L15 12.3301Z\" fill=\"white\" \/>\n                            <\/svg>\n                        <\/div>\n                    <\/div>\n                    \t\t\t\t\n\n         \n                <\/div>\n\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n\n\n<div loading=\"lazy\" class=\"block trustpilot\">\n    <div class=\"grid-container\">\n        <div class=\"grid-x\">\n            \n<div class=\"cell large-12 text-center\">\n  <div class=\"title-holder\">\n\n\n\n                          <h6>Consultez nos<\/h6>\n                    \n                                    <h2>avis sur Trustpilot<\/h2>\n                      <\/div>           \n<\/div>\n        <\/div>\n        <div class=\"box\">\n            <div class=\"grid-x\">\n                <div class=\"cell large-12\">\n                    <div class=\"background box-shadow border-radius\">\n                        \n                        <div class=\"grid-x align-center align-middle grid-margin-x grid-margin-y\">\n                            <div class=\"cell small-6 medium-4 large-2 text-center\">\n                                <h3>Excellent<\/h3>\n\n                                <a class=\"load\" href=\"https:\/\/www.trustpilot.com\/review\/www.amberscript.com?languages=fr\" target=\"_blank\" rel=\"noopener\">\n                                    <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/cdn.trustpilot.net\/brand-assets\/4.1.0\/stars\/stars-4.5.svg\" class=\"load\" alt=\"\" class=\"general-stars\">\n                                \n                                <small>Bas\u00e9 sur <b>376 commentaires<\/b><\/small>\n                                <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/trustpilot.svg\" loading=\"lazy\"  class=\"trustpilot-logo\" alt=\"Trustpilot\">\n                                <\/a>\n                            <\/div>\n                            <div class=\"cell large-10\">\n\n                                <div class=\"trust-pilot-slider\">\n                                                                    \n                                                                                \n                                        <div class=\"carousel-cell\">\n                                            <div class=\"grid-x\">\n                                                <div class=\"small-12\">\n                                                    <div class=\"rate-image load\">\n                                                        <img decoding=\"async\" src=\"https:\/\/cdn.trustpilot.net\/brand-assets\/4.1.0\/stars\/stars-5.svg\" loading=\"lazy\" alt=\"Trustpilot\" class=\"load\">\n                                                    <\/div>\n                                                <\/div>\n                                                <div class=\"small-12\">\n                                                    <div class=\"inner\">\n                                                        \n                                                                                                                    <h5>Tr\u00e8s bonne exp\u00e9rience g\u00e9n\u00e9rale.<\/h5>\n                                                                                                                <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                                <div class=\"small-12\">\n                                                    <div class=\"inner\">\n                                                                                                                    Tr\u00e8s bonne exp\u00e9rience g\u00e9n\u00e9rale. L&rsquo;outil est &#8230;                                                                                                                <p><\/p>\n                                                        <span>Cyril Motte<\/span>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n                                        <\/div>\n                                        \n                                        \n                                        <div class=\"carousel-cell\">\n                                            <div class=\"grid-x\">\n                                                <div class=\"small-12\">\n                                                    <div class=\"rate-image load\">\n                                                        <img decoding=\"async\" src=\"https:\/\/cdn.trustpilot.net\/brand-assets\/4.1.0\/stars\/stars-5.svg\" loading=\"lazy\" alt=\"Trustpilot\" class=\"load\">\n                                                    <\/div>\n                                                <\/div>\n                                                <div class=\"small-12\">\n                                                    <div class=\"inner\">\n                                                        \n                                                                                                                    <h5>Super application qui m&rsquo;a fait gagner\u2026<\/h5>\n                                                                                                                <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                                <div class=\"small-12\">\n                                                    <div class=\"inner\">\n                                                                                                                    Super application qui m&rsquo;a fait gagner un temps consid\u00e9rable &#8230;                                                                                                                <p><\/p>\n                                                        <span>Virginie Gvs<\/span>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n                                        <\/div>\n                                        \n                                        \n                                        <div class=\"carousel-cell\">\n                                            <div class=\"grid-x\">\n                                                <div class=\"small-12\">\n                                                    <div class=\"rate-image load\">\n                                                        <img decoding=\"async\" src=\"https:\/\/cdn.trustpilot.net\/brand-assets\/4.1.0\/stars\/stars-5.svg\" loading=\"lazy\" alt=\"Trustpilot\" class=\"load\">\n                                                    <\/div>\n                                                <\/div>\n                                                <div class=\"small-12\">\n                                                    <div class=\"inner\">\n                                                        \n                                                                                                                    <h5>Gain de temps et efficacit\u00e9<\/h5>\n                                                                                                                <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                                <div class=\"small-12\">\n                                                    <div class=\"inner\">\n                                                                                                                    M&rsquo;a fait gagner beaucoup de temps sur l&rsquo;\u00e9criture d&rsquo;un &#8230;                                                                                                                <p><\/p>\n                                                        <span>Sarah<\/span>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n                                        <\/div>\n                                        \n                                        \n                                        <div class=\"carousel-cell\">\n                                            <div class=\"grid-x\">\n                                                <div class=\"small-12\">\n                                                    <div class=\"rate-image load\">\n                                                        <img decoding=\"async\" src=\"https:\/\/cdn.trustpilot.net\/brand-assets\/4.1.0\/stars\/stars-5.svg\" loading=\"lazy\" alt=\"Trustpilot\" class=\"load\">\n                                                    <\/div>\n                                                <\/div>\n                                                <div class=\"small-12\">\n                                                    <div class=\"inner\">\n                                                        \n                                                                                                                    <h5>Transcription en fran\u00e7ais<\/h5>\n                                                                                                                <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                                <div class=\"small-12\">\n                                                    <div class=\"inner\">\n                                                                                                                    La transcription en fran\u00e7ais est exacte, tr\u00e8s facile \u00e0 &#8230;                                                                                                                <p><\/p>\n                                                        <span>Eileen Bernal Gallego<\/span>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n                                        <\/div>\n                                        \n                                        \n                                        <div class=\"carousel-cell\">\n                                            <div class=\"grid-x\">\n                                                <div class=\"small-12\">\n                                                    <div class=\"rate-image load\">\n                                                        <img decoding=\"async\" src=\"https:\/\/cdn.trustpilot.net\/brand-assets\/4.1.0\/stars\/stars-5.svg\" loading=\"lazy\" alt=\"Trustpilot\" class=\"load\">\n                                                    <\/div>\n                                                <\/div>\n                                                <div class=\"small-12\">\n                                                    <div class=\"inner\">\n                                                        \n                                                                                                                    <h5>Rapide et efficace<\/h5>\n                                                                                                                <\/h5>\n                                                    <\/div>\n                                                <\/div>\n                                                <div class=\"small-12\">\n                                                    <div class=\"inner\">\n                                                                                                                    Bon site, rapide et efficace pour transcrire ses fichiers audio. &#8230;                                                                                                                <p><\/p>\n                                                        <span>Guillaume<\/span>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n                                        <\/div>\n                                        \n                                                                                                                                                                                \n                                <\/div>\n                            <\/div>\n                        <\/div>\n\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<\/div>\n\n<div class=\"block accordion\">\n\t<div class=\"grid-container\" itemscope itemtype=\"https:\/\/schema.org\/FAQPage\">\n        <div class=\"grid-x align-center grid-margin-x grid-margin-y\">\n            \n<div class=\"cell large-12 text-center\">\n  <div class=\"title-holder\">\n\n\n\n                          <h6><span id=\"foire-aux-questions\"><\/span><h2><\/h6>\n                    \n                                    <h2>Foire aux questions<\/h2>\n                      <\/div>           \n<\/div>\n\n            \n            <div class=\"cell medium-10 large-5 \">\n                                    <ul class=\"accordion\" data-accordion  data-allow-all-closed=\"true\">\n                                            <li class=\"accordion-item\" data-accordion-item itemscope itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\">\n                            <a href=\"#\" class=\"accordion-title\">\n\t\t\t\t\t\t\t\t<div itemprop=\"name\">\n                            \t\tQuels sont les avantages de la conversion de fichiers audio en fichiers texte ?\t\t\t\t\t\t\t\t<\/div>\n                            <\/a>\n                            <div class=\"accordion-content\" data-tab-content itemscope itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\">\n\t\t\t\t\t\t\t\t<div itemprop=\"text\">\n\t\t                            <p>Lorsque vous convertissez des donn\u00e9es audio en texte, ce que l&rsquo;on appelle la transcription, vous rendez votre contenu plus accessible aux personnes souffrant de d\u00e9ficiences auditives ou ne parlant pas la m\u00eame langue. La transcription peut \u00e9galement faciliter le r\u00e9f\u00e9rencement de votre site web dans les moteurs de recherche tels que Google.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n                            <\/div>\n                        <\/li>\n                                            <li class=\"accordion-item\" data-accordion-item itemscope itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\">\n                            <a href=\"#\" class=\"accordion-title\">\n\t\t\t\t\t\t\t\t<div itemprop=\"name\">\n                            \t\tPuis-je convertir des vid\u00e9os en texte ?\t\t\t\t\t\t\t\t<\/div>\n                            <\/a>\n                            <div class=\"accordion-content\" data-tab-content itemscope itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\">\n\t\t\t\t\t\t\t\t<div itemprop=\"text\">\n\t\t                            <p>Oui, vous pouvez utiliser nos services automatis\u00e9s ou manuels pour obtenir une transcription de l&rsquo;audio de vos vid\u00e9os et pour obtenir des sous-titres pour vos vid\u00e9os.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n                            <\/div>\n                        <\/li>\n                                            <li class=\"accordion-item\" data-accordion-item itemscope itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\">\n                            <a href=\"#\" class=\"accordion-title\">\n\t\t\t\t\t\t\t\t<div itemprop=\"name\">\n                            \t\tComment puis-je modifier la transcription ?\t\t\t\t\t\t\t\t<\/div>\n                            <\/a>\n                            <div class=\"accordion-content\" data-tab-content itemscope itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\">\n\t\t\t\t\t\t\t\t<div itemprop=\"text\">\n\t\t                            <p>Vous pouvez facilement \u00e9diter et v\u00e9rifier votre fichier texte en utilisant notre \u00e9diteur en ligne. Il fonctionne comme un traitement de texte standard.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n                            <\/div>\n                        <\/li>\n                                        <\/ul>\n                            <\/div>\n            <div class=\"cell medium-10 large-5 large-offset-1\">\n                                <ul class=\"accordion\" data-accordion  data-allow-all-closed=\"true\">\n                                    <li class=\"accordion-item\" data-accordion-item itemscope itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\">\n                        <a href=\"#\" class=\"accordion-title\">\n\t\t\t\t\t\t\t<div itemprop=\"name\">\n                            Offrez-vous une transcription gratuite ?\t\t\t\t\t\t\t<\/div>\n                        <\/a>\n                        <div class=\"accordion-content\" data-tab-content itemscope itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\">\n\t\t\t\t\t\t      <div itemprop=\"text\">\n\t\t                        <p>Oui, vous obtiendrez automatiquement 10 minutes de transcription gratuite lorsque vous cr\u00e9erez un compte sur Amberscript.<\/p>\n\t\t\t\t\t\t\t<\/div>\n                        <\/div>\n                    <\/li>\n                                    <li class=\"accordion-item\" data-accordion-item itemscope itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\">\n                        <a href=\"#\" class=\"accordion-title\">\n\t\t\t\t\t\t\t<div itemprop=\"name\">\n                            Puis-je t\u00e9l\u00e9charger \u00e0 la fois le fichier TXT et la vid\u00e9o avec les sous-titres ?\t\t\t\t\t\t\t<\/div>\n                        <\/a>\n                        <div class=\"accordion-content\" data-tab-content itemscope itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\">\n\t\t\t\t\t\t      <div itemprop=\"text\">\n\t\t                        <p>Oui, vous pouvez t\u00e9l\u00e9charger un fichier texte s\u00e9par\u00e9 ou choisir de graver les sous-titres dans le fichier vid\u00e9o.<\/p>\n\t\t\t\t\t\t\t<\/div>\n                        <\/div>\n                    <\/li>\n                                    <li class=\"accordion-item\" data-accordion-item itemscope itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\">\n                        <a href=\"#\" class=\"accordion-title\">\n\t\t\t\t\t\t\t<div itemprop=\"name\">\n                            Quelle est la pr\u00e9cision du service de transcription d&rsquo;Amberscript ?\t\t\t\t\t\t\t<\/div>\n                        <\/a>\n                        <div class=\"accordion-content\" data-tab-content itemscope itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\">\n\t\t\t\t\t\t      <div itemprop=\"text\">\n\t\t                        <p>Pour une conversion audio\/texte rapide et abordable, nos services de transcription automatique transcrivent automatiquement le fichier avec une pr\u00e9cision pouvant atteindre 85 %, en fonction de la qualit\u00e9 de l&rsquo;audio.<\/p>\n<p>Nos services de transcription manuelle utilisent une combinaison unique de transcripteurs professionnels et de reconnaissance automatique de la parole pour cr\u00e9er des fichiers texte d&rsquo;une pr\u00e9cision de 100 %.<\/p>\n\t\t\t\t\t\t\t<\/div>\n                        <\/div>\n                    <\/li>\n                                <\/ul>\n                        <\/div>\n\n        \n            \n            \n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n\n    \n<div class=\"block color-banners\">\n    <div class=\"background\">\n        <div class=\"background theme-color-secondary \">\n            <div class=\"bg-shape\">\n                <svg width=\"451px\" height=\"240px\" viewBox=\"0 0 451 240\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" class=\"bg-shape\">\n    <title>Shape<\/title>\n    <g id=\"Page-1\" stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\">\n        <path d=\"M3.94,183.858 C6.505,181.288 9.64,180.001 13.346,180.001 L16.766,180.001 C20.466,180.001 23.605,181.287 26.17,183.858 C28.736,186.428 30.018,189.571 30.018,193.288 L30.018,196.714 C30.018,200.426 31.301,203.574 33.868,206.145 C36.43,208.715 39.564,210.002 43.27,210.002 L46.691,210.002 C50.392,210.002 53.532,208.715 56.095,206.145 C58.66,203.573 59.945,200.425 59.945,196.715 L59.945,193.288 C59.945,189.571 61.226,186.428 63.791,183.858 C66.357,181.288 69.488,180.001 73.197,180.001 L76.617,180.001 C80.317,180.001 83.456,181.287 86.022,183.858 C88.585,186.428 89.869,189.571 89.869,193.288 L89.869,196.714 C89.869,200.426 91.149,203.574 93.716,206.145 C96.281,208.715 99.412,210.002 103.122,210.002 L106.54,210.002 C110.24,210.002 113.38,208.715 115.946,206.145 C118.512,203.573 119.793,200.425 119.793,196.715 L119.793,193.288 C119.793,189.571 121.077,186.428 123.64,183.858 C126.206,181.288 129.34,180.001 133.046,180.001 L136.467,180.001 C140.167,180.001 143.305,181.287 145.871,183.858 C148.436,186.428 149.717,189.571 149.717,193.288 L149.717,196.714 C149.717,200.426 151.001,203.574 153.567,206.145 C156.132,208.715 159.263,210.002 162.97,210.002 L166.391,210.002 C170.091,210.002 173.231,208.715 175.797,206.145 C178.36,203.573 179.644,200.425 179.644,196.715 L179.644,193.288 C179.644,189.571 180.926,186.428 183.491,183.858 C186.056,181.288 189.188,180.001 192.897,180.001 L196.316,180.001 C200.016,180.001 203.156,181.287 205.722,183.858 C208.287,186.428 209.568,189.571 209.568,193.288 L209.568,196.714 C209.568,200.426 210.849,203.574 213.415,206.145 C215.981,208.715 219.115,210.002 222.82,210.002 L226.24,210.002 C229.94,210.002 233.08,208.715 235.645,206.145 C238.211,203.573 239.492,200.425 239.492,196.715 L239.492,193.288 C239.492,189.571 240.777,186.428 243.342,183.858 C245.904,181.288 249.039,180.001 252.745,180.001 L256.167,180.001 C259.867,180.001 263.007,181.287 265.57,183.858 C268.135,186.428 269.42,189.571 269.42,193.288 L269.42,196.714 C269.42,200.426 270.7,203.574 273.266,206.145 C275.832,208.715 278.963,210.002 282.672,210.002 L436.84,210.002 C440.54,210.002 443.681,211.286 446.246,213.857 C448.812,216.431 450.093,219.57 450.093,223.287 L450.093,226.716 C450.093,230.424 448.813,233.572 446.246,236.143 C443.681,238.714 440.54,240 436.84,240 L282.672,240 C278.962,240 275.832,238.714 273.266,236.143 C270.7,233.572 269.42,230.424 269.42,226.716 L269.42,223.286 C269.42,219.57 268.135,216.431 265.57,213.857 C263.007,211.286 259.867,210.002 256.167,210.002 L252.745,210.002 C249.039,210.002 245.905,211.286 243.342,213.857 C240.777,216.431 239.492,219.57 239.492,223.287 L239.492,226.716 C239.492,230.424 238.212,233.572 235.645,236.143 C233.08,238.714 229.94,240 226.24,240 L222.82,240 C219.115,240 215.98,238.714 213.415,236.143 C210.849,233.572 209.568,230.424 209.568,226.716 L209.568,223.286 C209.568,219.57 208.287,216.431 205.722,213.857 C203.156,211.286 200.016,210.002 196.316,210.002 L192.896,210.002 C189.188,210.002 186.056,211.286 183.491,213.857 C180.926,216.431 179.644,219.57 179.644,223.287 L179.644,226.716 C179.644,230.424 178.36,233.572 175.797,236.143 C173.232,238.714 170.092,240 166.391,240 L162.971,240 C159.263,240 156.132,238.714 153.567,236.143 C151.001,233.572 149.717,230.424 149.717,226.716 L149.717,223.286 C149.717,219.57 148.436,216.431 145.871,213.857 C143.305,211.286 140.167,210.002 136.467,210.002 L133.046,210.002 C129.34,210.002 126.206,211.286 123.64,213.857 C121.077,216.431 119.793,219.57 119.793,223.287 L119.793,226.716 C119.793,230.424 118.512,233.572 115.946,236.143 C113.381,238.714 110.24,240 106.54,240 L103.122,240 C99.412,240 96.281,238.714 93.716,236.143 C91.15,233.572 89.869,230.424 89.869,226.716 L89.869,223.286 C89.869,219.57 88.585,216.431 86.022,213.857 C83.456,211.286 80.316,210.002 76.616,210.002 L73.197,210.002 C69.488,210.002 66.357,211.286 63.791,213.857 C61.226,216.431 59.945,219.57 59.945,223.287 L59.945,226.716 C59.945,230.424 58.66,233.572 56.095,236.143 C53.532,238.714 50.392,240 46.691,240 L43.27,240 C39.564,240 36.43,238.714 33.867,236.143 C31.301,233.572 30.017,230.424 30.017,226.716 L30.017,223.286 C30.017,219.57 28.737,216.431 26.17,213.857 C23.605,211.286 20.465,210.002 16.765,210.002 L13.346,210.002 C9.64,210.002 6.506,208.715 3.94,206.145 C1.375,203.573 0.093,200.425 0.093,196.715 L0.093,193.288 C0.093,189.571 1.375,186.428 3.94,183.858 M3.94,123.858 C6.505,121.288 9.64,120 13.346,120 L16.766,120 C20.466,120 23.605,121.287 26.17,123.858 C28.736,126.428 30.018,129.571 30.018,133.288 L30.018,136.714 C30.018,140.425 31.301,143.574 33.868,146.144 C36.43,148.716 39.564,150.001 43.27,150.001 L46.691,150.001 C50.392,150.001 53.532,148.716 56.095,146.144 C58.66,143.574 59.945,140.425 59.945,136.714 L59.945,133.288 C59.945,129.571 61.226,126.428 63.791,123.858 C66.357,121.288 69.488,120 73.197,120 L76.617,120 C80.317,120 83.456,121.287 86.022,123.858 C88.585,126.428 89.869,129.571 89.869,133.288 L89.869,136.714 C89.869,140.425 91.149,143.574 93.716,146.144 C96.281,148.716 99.412,150.001 103.122,150.001 L106.54,150.001 C110.24,150.001 113.38,148.716 115.946,146.144 C118.512,143.574 119.793,140.425 119.793,136.714 L119.793,133.288 C119.793,129.571 121.077,126.428 123.64,123.858 C126.206,121.288 129.34,120 133.046,120 L136.467,120 C140.167,120 143.305,121.287 145.871,123.858 C148.436,126.428 149.717,129.571 149.717,133.288 L149.717,136.714 C149.717,140.425 151.001,143.574 153.567,146.144 C156.132,148.716 159.263,150.001 162.97,150.001 L166.391,150.001 C170.091,150.001 173.231,148.716 175.797,146.144 C178.36,143.574 179.644,140.425 179.644,136.714 L179.644,133.288 C179.644,129.571 180.926,126.428 183.491,123.858 C186.056,121.288 189.188,120 192.897,120 L196.316,120 C200.016,120 203.156,121.287 205.722,123.858 C208.287,126.428 209.568,129.571 209.568,133.288 L209.568,136.714 C209.568,140.425 210.849,143.574 213.415,146.144 C215.981,148.716 219.115,150.001 222.82,150.001 L226.24,150.001 C229.94,150.001 233.08,148.716 235.645,146.144 C238.211,143.574 239.492,140.425 239.492,136.714 L239.492,133.288 C239.492,129.571 240.777,126.428 243.342,123.858 C245.904,121.288 249.039,120 252.745,120 L256.167,120 C259.867,120 263.007,121.287 265.57,123.858 C268.135,126.428 269.42,129.571 269.42,133.288 L269.42,136.714 C269.42,140.425 270.7,143.574 273.266,146.144 C275.832,148.716 278.963,150.001 282.672,150.001 L436.84,150.001 C440.54,150.001 443.681,151.285 446.246,153.859 C448.812,156.43 450.093,159.569 450.093,163.287 L450.093,166.716 C450.093,170.425 448.813,173.573 446.246,176.143 C443.681,178.717 440.54,180.001 436.84,180.001 L282.672,180.001 C278.962,180.001 275.832,178.717 273.266,176.143 C270.7,173.573 269.42,170.425 269.42,166.716 L269.42,163.287 C269.42,159.57 268.135,156.43 265.57,153.859 C263.007,151.285 259.867,150.001 256.167,150.001 L252.745,150.001 C249.039,150.001 245.905,151.285 243.342,153.859 C240.777,156.43 239.492,159.569 239.492,163.287 L239.492,166.716 C239.492,170.425 238.212,173.573 235.645,176.143 C233.08,178.717 229.94,180.001 226.24,180.001 L222.82,180.001 C219.115,180.001 215.98,178.717 213.415,176.143 C210.849,173.573 209.568,170.425 209.568,166.716 L209.568,163.287 C209.568,159.57 208.287,156.43 205.722,153.859 C203.156,151.285 200.016,150.001 196.316,150.001 L192.896,150.001 C189.188,150.001 186.056,151.285 183.491,153.859 C180.926,156.43 179.644,159.569 179.644,163.287 L179.644,166.716 C179.644,170.425 178.36,173.573 175.797,176.143 C173.232,178.717 170.092,180.001 166.391,180.001 L162.971,180.001 C159.263,180.001 156.132,178.717 153.567,176.143 C151.001,173.573 149.717,170.425 149.717,166.716 L149.717,163.287 C149.717,159.57 148.436,156.43 145.871,153.859 C143.305,151.285 140.167,150.001 136.467,150.001 L133.046,150.001 C129.34,150.001 126.206,151.285 123.64,153.859 C121.077,156.43 119.793,159.569 119.793,163.287 L119.793,166.716 C119.793,170.425 118.512,173.573 115.946,176.143 C113.381,178.717 110.24,180.001 106.54,180.001 L103.122,180.001 C99.412,180.001 96.281,178.717 93.716,176.143 C91.15,173.573 89.869,170.425 89.869,166.716 L89.869,163.287 C89.869,159.57 88.585,156.43 86.022,153.859 C83.456,151.285 80.316,150.001 76.616,150.001 L73.197,150.001 C69.488,150.001 66.357,151.285 63.791,153.859 C61.226,156.43 59.945,159.569 59.945,163.287 L59.945,166.716 C59.945,170.425 58.66,173.573 56.095,176.143 C53.532,178.717 50.392,180.001 46.691,180.001 L43.27,180.001 C39.564,180.001 36.43,178.717 33.867,176.143 C31.301,173.573 30.017,170.425 30.017,166.716 L30.017,163.287 C30.017,159.57 28.737,156.43 26.17,153.859 C23.605,151.285 20.465,150.001 16.765,150.001 L13.346,150.001 C9.64,150.001 6.506,148.716 3.94,146.144 C1.375,143.574 0.093,140.425 0.093,136.714 L0.093,133.288 C0.093,129.571 1.375,126.428 3.94,123.858 M3.94,63.858 C6.505,61.287 9.64,60 13.346,60 L16.766,60 C20.466,60 23.605,61.287 26.17,63.858 C28.736,66.429 30.018,69.571 30.018,73.288 L30.018,76.715 C30.018,80.425 31.301,83.574 33.868,86.144 C36.43,88.714 39.564,90.002 43.27,90.002 L46.691,90.002 C50.392,90.002 53.532,88.715 56.095,86.144 C58.66,83.574 59.945,80.425 59.945,76.714 L59.945,73.288 C59.945,69.571 61.226,66.429 63.791,63.858 C66.357,61.287 69.488,60 73.197,60 L76.617,60 C80.317,60 83.456,61.287 86.022,63.858 C88.585,66.429 89.869,69.571 89.869,73.288 L89.869,76.715 C89.869,80.425 91.149,83.574 93.716,86.144 C96.281,88.714 99.412,90.002 103.122,90.002 L106.54,90.002 C110.24,90.002 113.38,88.715 115.946,86.144 C118.512,83.574 119.793,80.425 119.793,76.714 L119.793,73.288 C119.793,69.571 121.077,66.429 123.64,63.858 C126.206,61.287 129.34,60 133.046,60 L136.467,60 C140.167,60 143.305,61.287 145.871,63.858 C148.436,66.429 149.717,69.571 149.717,73.288 L149.717,76.715 C149.717,80.425 151.001,83.574 153.567,86.144 C156.132,88.714 159.263,90.002 162.97,90.002 L166.391,90.002 C170.091,90.002 173.231,88.715 175.797,86.144 C178.36,83.574 179.644,80.425 179.644,76.714 L179.644,73.288 C179.644,69.571 180.926,66.429 183.491,63.858 C186.056,61.287 189.188,60 192.897,60 L196.316,60 C200.016,60 203.156,61.287 205.722,63.858 C208.287,66.429 209.568,69.571 209.568,73.288 L209.568,76.715 C209.568,80.425 210.849,83.574 213.415,86.144 C215.981,88.714 219.115,90.002 222.82,90.002 L226.24,90.002 C229.94,90.002 233.08,88.715 235.645,86.144 C238.211,83.574 239.492,80.425 239.492,76.714 L239.492,73.288 C239.492,69.571 240.777,66.429 243.342,63.858 C245.904,61.287 249.039,60 252.745,60 L256.167,60 C259.867,60 263.007,61.287 265.57,63.858 C268.135,66.429 269.42,69.571 269.42,73.288 L269.42,76.715 C269.42,80.425 270.7,83.574 273.266,86.144 C275.832,88.714 278.963,90.002 282.672,90.002 L436.84,90.002 C440.54,90.002 443.681,91.286 446.246,93.859 C448.812,96.43 450.093,99.57 450.093,103.286 L450.093,106.716 C450.093,110.424 448.813,113.572 446.246,116.143 C443.681,118.716 440.54,120 436.84,120 L282.672,120 C278.962,120 275.832,118.716 273.266,116.143 C270.7,113.573 269.42,110.424 269.42,106.716 L269.42,103.286 C269.42,99.57 268.135,96.43 265.57,93.859 C263.007,91.286 259.867,90.002 256.167,90.002 L252.745,90.002 C249.039,90.002 245.905,91.286 243.342,93.859 C240.777,96.43 239.492,99.57 239.492,103.286 L239.492,106.716 C239.492,110.424 238.212,113.572 235.645,116.143 C233.08,118.716 229.94,120 226.24,120 L222.82,120 C219.115,120 215.98,118.716 213.415,116.143 C210.849,113.573 209.568,110.424 209.568,106.716 L209.568,103.286 C209.568,99.57 208.287,96.43 205.722,93.859 C203.156,91.286 200.016,90.002 196.316,90.002 L192.896,90.002 C189.188,90.002 186.056,91.286 183.491,93.859 C180.926,96.43 179.644,99.57 179.644,103.286 L179.644,106.716 C179.644,110.424 178.36,113.572 175.797,116.143 C173.232,118.716 170.092,120 166.391,120 L162.971,120 C159.263,120 156.132,118.716 153.567,116.143 C151.001,113.573 149.717,110.424 149.717,106.716 L149.717,103.286 C149.717,99.57 148.436,96.43 145.871,93.859 C143.305,91.286 140.167,90.002 136.467,90.002 L133.046,90.002 C129.34,90.002 126.206,91.286 123.64,93.859 C121.077,96.43 119.793,99.57 119.793,103.286 L119.793,106.716 C119.793,110.424 118.512,113.572 115.946,116.143 C113.381,118.716 110.24,120 106.54,120 L103.122,120 C99.412,120 96.281,118.716 93.716,116.143 C91.15,113.573 89.869,110.424 89.869,106.716 L89.869,103.286 C89.869,99.57 88.585,96.43 86.022,93.859 C83.456,91.286 80.316,90.002 76.616,90.002 L73.197,90.002 C69.488,90.002 66.357,91.286 63.791,93.859 C61.226,96.43 59.945,99.57 59.945,103.286 L59.945,106.716 C59.945,110.424 58.66,113.572 56.095,116.143 C53.532,118.716 50.392,120 46.691,120 L43.27,120 C39.564,120 36.43,118.716 33.867,116.143 C31.301,113.573 30.017,110.424 30.017,106.716 L30.017,103.286 C30.017,99.57 28.737,96.43 26.17,93.859 C23.605,91.286 20.465,90.002 16.765,90.002 L13.346,90.002 C9.64,90.002 6.506,88.715 3.94,86.144 C1.375,83.574 0.093,80.425 0.093,76.714 L0.093,73.288 C0.093,69.571 1.375,66.429 3.94,63.858 M13.346,0 L16.766,0 C20.466,0 23.605,1.287 26.17,3.857 C28.736,6.431 30.018,9.571 30.018,13.287 L30.018,16.714 C30.018,20.426 31.301,23.574 33.868,26.144 C36.43,28.714 39.564,30.002 43.27,30.002 L46.691,30.002 C50.392,30.002 53.532,28.714 56.095,26.144 C58.66,23.574 59.945,20.426 59.945,16.714 L59.945,13.287 C59.945,9.571 61.226,6.431 63.791,3.857 C66.357,1.287 69.488,0 73.197,0 L76.617,0 C80.317,0 83.456,1.287 86.022,3.857 C88.585,6.431 89.869,9.571 89.869,13.287 L89.869,16.714 C89.869,20.426 91.149,23.574 93.716,26.144 C96.281,28.714 99.412,30.002 103.122,30.002 L106.54,30.002 C110.24,30.002 113.38,28.714 115.946,26.144 C118.512,23.574 119.793,20.426 119.793,16.714 L119.793,13.287 C119.793,9.571 121.077,6.431 123.64,3.857 C126.206,1.287 129.34,0 133.046,0 L136.467,0 C140.167,0 143.305,1.287 145.871,3.857 C148.436,6.431 149.717,9.571 149.717,13.287 L149.717,16.714 C149.717,20.426 151.001,23.574 153.567,26.144 C156.132,28.714 159.263,30.002 162.97,30.002 L166.391,30.002 C170.091,30.002 173.231,28.714 175.797,26.144 C178.36,23.574 179.644,20.426 179.644,16.714 L179.644,13.287 C179.644,9.571 180.926,6.431 183.491,3.857 C186.056,1.287 189.188,0 192.897,0 L196.316,0 C200.016,0 203.156,1.287 205.722,3.857 C208.287,6.431 209.568,9.571 209.568,13.287 L209.568,16.714 C209.568,20.426 210.849,23.574 213.415,26.144 C215.981,28.714 219.115,30.002 222.82,30.002 L226.24,30.002 C229.94,30.002 233.08,28.714 235.645,26.144 C238.211,23.574 239.492,20.426 239.492,16.714 L239.492,13.287 C239.492,9.571 240.777,6.431 243.342,3.857 C245.904,1.287 249.039,0 252.745,0 L256.167,0 C259.867,0 263.007,1.287 265.57,3.857 C268.135,6.431 269.42,9.571 269.42,13.287 L269.42,16.714 C269.42,20.426 270.7,23.574 273.266,26.144 C275.832,28.714 278.963,30.002 282.672,30.002 L436.84,30.002 C440.54,30.002 443.681,31.285 446.246,33.859 C448.812,36.429 450.093,39.569 450.093,43.286 L450.093,46.716 C450.093,50.423 448.813,53.572 446.246,56.143 C443.681,58.716 440.54,60 436.84,60 L282.672,60 C278.962,60 275.832,58.716 273.266,56.143 C270.7,53.573 269.42,50.423 269.42,46.715 L269.42,43.285 C269.42,39.569 268.135,36.43 265.57,33.859 C263.007,31.285 259.867,30.002 256.167,30.002 L252.745,30.002 C249.039,30.002 245.905,31.285 243.342,33.859 C240.777,36.429 239.492,39.569 239.492,43.286 L239.492,46.716 C239.492,50.423 238.212,53.572 235.645,56.143 C233.08,58.716 229.94,60 226.24,60 L222.82,60 C219.115,60 215.98,58.716 213.415,56.143 C210.849,53.573 209.568,50.423 209.568,46.715 L209.568,43.285 C209.568,39.569 208.287,36.43 205.722,33.859 C203.156,31.285 200.016,30.002 196.316,30.002 L192.896,30.002 C189.188,30.002 186.056,31.285 183.491,33.859 C180.926,36.429 179.644,39.569 179.644,43.286 L179.644,46.716 C179.644,50.423 178.36,53.572 175.797,56.143 C173.232,58.716 170.092,60 166.391,60 L162.971,60 C159.263,60 156.132,58.716 153.567,56.143 C151.001,53.573 149.717,50.423 149.717,46.715 L149.717,43.285 C149.717,39.569 148.436,36.43 145.871,33.859 C143.305,31.285 140.167,30.002 136.467,30.002 L133.046,30.002 C129.34,30.002 126.206,31.285 123.64,33.859 C121.077,36.429 119.793,39.569 119.793,43.286 L119.793,46.716 C119.793,50.423 118.512,53.572 115.946,56.143 C113.38,58.716 110.24,60 106.54,60 L103.122,60 C99.412,60 96.281,58.716 93.716,56.143 C91.15,53.573 89.869,50.423 89.869,46.715 L89.869,43.285 C89.869,39.569 88.585,36.43 86.022,33.859 C83.456,31.285 80.316,30.002 76.616,30.002 L73.197,30.002 C69.488,30.002 66.357,31.285 63.791,33.859 C61.226,36.429 59.945,39.569 59.945,43.286 L59.945,46.716 C59.945,50.423 58.66,53.572 56.095,56.143 C53.532,58.716 50.392,60 46.69,60 L43.27,60 C39.564,60 36.43,58.716 33.867,56.143 C31.301,53.573 30.017,50.423 30.017,46.715 L30.017,43.285 C30.017,39.569 28.737,36.43 26.17,33.859 C23.605,31.285 20.465,30.002 16.765,30.002 L13.346,30.002 C9.64,30.002 6.506,28.714 3.94,26.144 C1.375,23.574 0.093,20.426 0.093,16.714 L0.093,13.287 C0.093,9.571 1.375,6.431 3.94,3.857 C6.505,1.287 9.64,0 13.346,0 Z\" id=\"Shape\" fill=\"#005A50\" fill-rule=\"nonzero\"><\/path>\n    <\/g>\n<\/svg>            <\/div>\n                <div class=\"grid-container\">\n                    <div class=\"grid-x align-center\">\n                        <div class=\"cell large-9 medium-12 small-10 text-center\">\n                        \n                                                        <div class=\"subtitle-prefix\">Remises sur volume et comptes multi-utilisateurs<\/div>\n                                                        <div class=\"title-prefix h2 heading\">Amberscript pour entreprises<\/div>\n                        \n                        <\/div>\n                                                <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        \n        <div class=\"grid-container\">\n            <div class=\"holder background theme-color-primary\">\n                                <div class=\"grid-container\">\n                        <div class=\"grid-x align-middle grid-margin-x\">\n\n                            <div class=\"cell large-1\">\n                                <div class=\"bg-shape-small\">\n                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"bg-shape-small\" width=\"103\" height=\"122\" viewBox=\"0 0 103 122\">\n    <g fill=\"none\" fill-rule=\"evenodd\">\n        <g fill=\"#F082A0\">\n            <g>\n                <g>\n                    <g>\n                        <path d=\"M31.426 53.334c-2.386-2.44-3.581-5.426-3.581-8.955V41.12c0-3.524-1.192-6.515-3.58-8.955-2.387-2.444-5.308-3.667-8.75-3.667H12.33c-3.45 0-6.365-1.22-8.751-3.663C1.192 22.391 0 19.409 0 15.877v-3.256c0-3.525 1.192-6.514 3.58-8.958C5.966 1.222 8.88 0 12.33 0h3.184c3.443 0 6.364 1.222 8.751 3.663 2.388 2.444 3.58 5.433 3.58 8.958v3.256c0 3.532 1.195 6.514 3.581 8.958 2.386 2.443 5.304 3.663 8.753 3.663h50.487c3.445 0 6.367 1.223 8.753 3.667 2.387 2.44 3.581 5.43 3.581 8.955v3.26c0 3.528-1.194 6.514-3.581 8.954C97.033 55.777 94.11 57 90.666 57H40.179c-3.45 0-6.367-1.223-8.753-3.666M71.574 68.666c2.386 2.44 3.581 5.426 3.581 8.955v3.259c0 3.524 1.19 6.515 3.58 8.955 2.387 2.443 5.308 3.667 8.75 3.667h3.184c3.45 0 6.365 1.22 8.751 3.663 2.388 2.443 3.58 5.425 3.58 8.958v3.256c0 3.523-1.192 6.514-3.58 8.958-2.386 2.441-5.301 3.663-8.75 3.663h-3.184c-3.443 0-6.364-1.222-8.751-3.663-2.39-2.444-3.58-5.435-3.58-8.958v-3.256c0-3.533-1.195-6.515-3.581-8.958-2.386-2.443-5.304-3.663-8.754-3.663H12.334c-3.445 0-6.367-1.224-8.753-3.667C1.194 87.395 0 84.405 0 80.88v-3.26c0-3.528 1.194-6.514 3.581-8.954C5.967 66.222 8.89 65 12.334 65H62.82c3.45 0 6.368 1.222 8.754 3.666\" transform=\"translate(-80 -3680) translate(0 3100) translate(80 580)\"\/>\n                    <\/g>\n                <\/g>\n            <\/g>\n        <\/g>\n    <\/g>\n<\/svg>                                <\/div>\n                            <\/div>\n                            <div class=\"cell medium-7 large-5 large-offset-1\">\n                                <h2>For business inquiries, please contact us.<\/h2>\n                            <\/div>\n                            <div class=\"cell medium-5 large-4 large-offset-1\">\n                                <div class=\"grid-x align-middle\">\n                                                                                                                                                            <div class=\"cell small-6 medium-shrink large-12 text-left\">\n                                  \n                                                    <a class=\"button theme-background-secondary\n                                                                                                            primary                                                                                                                                                            \" href=\"https:\/\/wp-staging.amberscript.com\/fr\/demandez-un-devis\/\" target=\"_self\">Demandez un devis<\/a>\n                                                <\/div>\n                                                \n                                                                                                                                                                            <div class=\"cell small-6 medium-shrink large-12 text-left\">\n                                  \n                                                    <a class=\"button theme-background-secondary\n                                                                                                                                                                                                                            theme-background-secondary\n                                                                                                                                                                \" href=\"https:\/\/wp-staging.amberscript.com\/fr\/demandez-un-devis\/\" target=\"_self\">Contacter le service des ventes<\/a>\n                                                <\/div>\n                                                \n                                                                                                                        \n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n\n\n\n\n\n    <div class=\"block holder product-relations layout-2         padding\">\n            <div class=\"grid-container\">\n        <div class=\"grid-x align-middle grid-margin-y grid-margin-x\">\n            \n            <div class=\"cell medium-6 large-4\">\n                <div class=\"title-holder\">\n                \n                                            <h2>Vous pourriez \u00eatre int\u00e9ress\u00e9 par des services de transcription pour votre secteur d&rsquo;activit\u00e9<\/h2>\n                                                            \n                <\/div>\n                                    <p>Pour en savoir plus, consultez nos exemples d&rsquo;utilisation et d\u00e9couvrez comment nos produits peuvent contribuer \u00e0 votre secteur d&rsquo;activit\u00e9 et l&rsquo;influencer.<\/p>\n                \n                                    <a class=\"button theme-color-secondary\" href=\"https:\/\/wp-staging.amberscript.com\/fr\/transcription-pour-industries\/\" target=\"_self\">En savoir plus<\/a>\n                            <\/div>\n\n\n            <div class=\"cell medium-6 large-7 large-offset-1\">\n                <div class=\"product-rel layout-2 background box-shadow\">\n\n                <div class=\"grid-x\">\n                    <div class=\"cell small-12 show-for-small hide-for-large\">\n                        <div class=\"responsive-slider\">\n                                                                                    <div class=\"cell\">\n                                    <div class=\"cell\">\n    <a href=\"https:\/\/wp-staging.amberscript.com\/fr\/?post_type=products&#038;p=8161\">\n        <div class=\"flip-card\">\n            <div class=\"flip-card-inner\">\n                <div class=\"flip-card-front\">\n                <div class=\"product-item\">\n                    <b>Transcription automatique<\/b>\n                    <div class=\"button primary black\">\n                        En savoir plus                    <\/div>\n                <\/div>\n                <\/div>\n                \n                <div class=\"flip-card-back theme-background-secondary\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape.svg\" class=\"shape-green-pink\" alt=\"\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape-blue.svg\" class=\"shape-green-blue\" alt=\"\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape-orange.svg\" class=\"shape-green-orange\" alt=\"\">\n                    \n                    <b>Transcription automatique<\/b>\n                    <p>Convertissez vos fichiers audio et vid\u00e9o gr\u00e2ce \u00e0 nos moteur d&rsquo;IA. <\/p>\n                <\/div>\n                \n            <\/div>\n        <\/div>\n    <\/a>\n    \n<\/div>                                <\/div>\n                                                            <div class=\"cell\">\n                                    <div class=\"cell\">\n    <a href=\"https:\/\/wp-staging.amberscript.com\/fr\/?post_type=products&#038;p=14791\">\n        <div class=\"flip-card\">\n            <div class=\"flip-card-inner\">\n                <div class=\"flip-card-front\">\n                <div class=\"product-item\">\n                    <b>Transcription professionnelle<\/b>\n                    <div class=\"button primary black\">\n                        En savoir plus                    <\/div>\n                <\/div>\n                <\/div>\n                \n                <div class=\"flip-card-back theme-background-secondary\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape.svg\" class=\"shape-green-pink\" alt=\"\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape-blue.svg\" class=\"shape-green-blue\" alt=\"\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape-orange.svg\" class=\"shape-green-orange\" alt=\"\">\n                    \n                    <b>Transcription professionnelle<\/b>\n                    <p>Laissez nos transcripteurs perfectionner votre texte. \n<\/p>\n                <\/div>\n                \n            <\/div>\n        <\/div>\n    <\/a>\n    \n<\/div>                                <\/div>\n                                                            <div class=\"cell\">\n                                    <div class=\"cell\">\n    <a href=\"https:\/\/wp-staging.amberscript.com\/fr\/?post_type=products&#038;p=14842\">\n        <div class=\"flip-card\">\n            <div class=\"flip-card-inner\">\n                <div class=\"flip-card-front\">\n                <div class=\"product-item\">\n                    <b>Sous-titres automatiques<\/b>\n                    <div class=\"button primary black\">\n                        En savoir plus                    <\/div>\n                <\/div>\n                <\/div>\n                \n                <div class=\"flip-card-back theme-background-secondary\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape.svg\" class=\"shape-green-pink\" alt=\"\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape-blue.svg\" class=\"shape-green-blue\" alt=\"\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape-orange.svg\" class=\"shape-green-orange\" alt=\"\">\n                    \n                    <b>Sous-titres automatiques<\/b>\n                    <p>Ajoutez des sous-titres \u00e0 vos vid\u00e9os gr\u00e2ce \u00e0 notre g\u00e9n\u00e9rateur de sous-titres.<\/p>\n                <\/div>\n                \n            <\/div>\n        <\/div>\n    <\/a>\n    \n<\/div>                                <\/div>\n                                                            <div class=\"cell\">\n                                    <div class=\"cell\">\n    <a href=\"https:\/\/wp-staging.amberscript.com\/fr\/?post_type=products&#038;p=15638\">\n        <div class=\"flip-card\">\n            <div class=\"flip-card-inner\">\n                <div class=\"flip-card-front\">\n                <div class=\"product-item\">\n                    <b>Sous-titres professionnels<\/b>\n                    <div class=\"button primary black\">\n                        En savoir plus                    <\/div>\n                <\/div>\n                <\/div>\n                \n                <div class=\"flip-card-back theme-background-secondary\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape.svg\" class=\"shape-green-pink\" alt=\"\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape-blue.svg\" class=\"shape-green-blue\" alt=\"\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape-orange.svg\" class=\"shape-green-orange\" alt=\"\">\n                    \n                    <b>Sous-titres professionnels<\/b>\n                    <p>Les sous-titres (traduits ou non) sont cr\u00e9\u00e9s et \u00e9dit\u00e9s par nos transcripteurs.<\/p>\n                <\/div>\n                \n            <\/div>\n        <\/div>\n    <\/a>\n    \n<\/div>                                <\/div>\n                                                            <div class=\"cell\">\n                                    <div class=\"cell\">\n    <a href=\"https:\/\/wp-staging.amberscript.com\/fr\/produits\/api-modeles-personnalises\/\">\n        <div class=\"flip-card\">\n            <div class=\"flip-card-inner\">\n                <div class=\"flip-card-front\">\n                <div class=\"product-item\">\n                    <b>API &#038; Mod\u00e8les personnalis\u00e9s<\/b>\n                    <div class=\"button primary black\">\n                        En savoir plus                    <\/div>\n                <\/div>\n                <\/div>\n                \n                <div class=\"flip-card-back theme-background-secondary\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape.svg\" class=\"shape-green-pink\" alt=\"\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape-blue.svg\" class=\"shape-green-blue\" alt=\"\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape-orange.svg\" class=\"shape-green-orange\" alt=\"\">\n                    \n                    <b>API &#038; Mod\u00e8les personnalis\u00e9s<\/b>\n                    <p>Ajoutez notre API et\/ou demandez un mod\u00e8le.<\/p>\n                <\/div>\n                \n            <\/div>\n        <\/div>\n    <\/a>\n    \n<\/div>                                <\/div>\n                                                            <div class=\"cell\">\n                                    <div class=\"cell\">\n    <a href=\"https:\/\/wp-staging.amberscript.com\/fr\/produits\/solutions-dentreprise\/\">\n        <div class=\"flip-card\">\n            <div class=\"flip-card-inner\">\n                <div class=\"flip-card-front\">\n                <div class=\"product-item\">\n                    <b>Solutions d&rsquo;entreprise<\/b>\n                    <div class=\"button primary black\">\n                        En savoir plus                    <\/div>\n                <\/div>\n                <\/div>\n                \n                <div class=\"flip-card-back theme-background-secondary\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape.svg\" class=\"shape-green-pink\" alt=\"\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape-blue.svg\" class=\"shape-green-blue\" alt=\"\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape-orange.svg\" class=\"shape-green-orange\" alt=\"\">\n                    \n                    <b>Solutions d&rsquo;entreprise<\/b>\n                    <p>Remises sur le volume, licence multi-utilisateurs, int\u00e9gration API et autres solution d&rsquo;entreprises.<\/p>\n                <\/div>\n                \n            <\/div>\n        <\/div>\n    <\/a>\n    \n<\/div>                                <\/div>\n                                                                        \n                        <\/div>\n                    <\/div>\n                <\/div>\n\n                <div class=\"grid-x show-for-large\">\n                                                                        <div class=\"cell medium-6 large-4\">\n                                <div class=\"cell\">\n    <a href=\"https:\/\/wp-staging.amberscript.com\/fr\/?post_type=products&#038;p=8161\">\n        <div class=\"flip-card\">\n            <div class=\"flip-card-inner\">\n                <div class=\"flip-card-front\">\n                <div class=\"product-item\">\n                    <b>Transcription automatique<\/b>\n                    <div class=\"button primary black\">\n                        En savoir plus                    <\/div>\n                <\/div>\n                <\/div>\n                \n                <div class=\"flip-card-back theme-background-secondary\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape.svg\" class=\"shape-green-pink\" alt=\"\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape-blue.svg\" class=\"shape-green-blue\" alt=\"\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape-orange.svg\" class=\"shape-green-orange\" alt=\"\">\n                    \n                    <b>Transcription automatique<\/b>\n                    <p>Convertissez vos fichiers audio et vid\u00e9o gr\u00e2ce \u00e0 nos moteur d&rsquo;IA. <\/p>\n                <\/div>\n                \n            <\/div>\n        <\/div>\n    <\/a>\n    \n<\/div>                            <\/div>\n                                                    <div class=\"cell medium-6 large-4\">\n                                <div class=\"cell\">\n    <a href=\"https:\/\/wp-staging.amberscript.com\/fr\/?post_type=products&#038;p=14791\">\n        <div class=\"flip-card\">\n            <div class=\"flip-card-inner\">\n                <div class=\"flip-card-front\">\n                <div class=\"product-item\">\n                    <b>Transcription professionnelle<\/b>\n                    <div class=\"button primary black\">\n                        En savoir plus                    <\/div>\n                <\/div>\n                <\/div>\n                \n                <div class=\"flip-card-back theme-background-secondary\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape.svg\" class=\"shape-green-pink\" alt=\"\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape-blue.svg\" class=\"shape-green-blue\" alt=\"\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape-orange.svg\" class=\"shape-green-orange\" alt=\"\">\n                    \n                    <b>Transcription professionnelle<\/b>\n                    <p>Laissez nos transcripteurs perfectionner votre texte. \n<\/p>\n                <\/div>\n                \n            <\/div>\n        <\/div>\n    <\/a>\n    \n<\/div>                            <\/div>\n                                                    <div class=\"cell medium-6 large-4\">\n                                <div class=\"cell\">\n    <a href=\"https:\/\/wp-staging.amberscript.com\/fr\/?post_type=products&#038;p=14842\">\n        <div class=\"flip-card\">\n            <div class=\"flip-card-inner\">\n                <div class=\"flip-card-front\">\n                <div class=\"product-item\">\n                    <b>Sous-titres automatiques<\/b>\n                    <div class=\"button primary black\">\n                        En savoir plus                    <\/div>\n                <\/div>\n                <\/div>\n                \n                <div class=\"flip-card-back theme-background-secondary\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape.svg\" class=\"shape-green-pink\" alt=\"\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape-blue.svg\" class=\"shape-green-blue\" alt=\"\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape-orange.svg\" class=\"shape-green-orange\" alt=\"\">\n                    \n                    <b>Sous-titres automatiques<\/b>\n                    <p>Ajoutez des sous-titres \u00e0 vos vid\u00e9os gr\u00e2ce \u00e0 notre g\u00e9n\u00e9rateur de sous-titres.<\/p>\n                <\/div>\n                \n            <\/div>\n        <\/div>\n    <\/a>\n    \n<\/div>                            <\/div>\n                                                    <div class=\"cell medium-6 large-4\">\n                                <div class=\"cell\">\n    <a href=\"https:\/\/wp-staging.amberscript.com\/fr\/?post_type=products&#038;p=15638\">\n        <div class=\"flip-card\">\n            <div class=\"flip-card-inner\">\n                <div class=\"flip-card-front\">\n                <div class=\"product-item\">\n                    <b>Sous-titres professionnels<\/b>\n                    <div class=\"button primary black\">\n                        En savoir plus                    <\/div>\n                <\/div>\n                <\/div>\n                \n                <div class=\"flip-card-back theme-background-secondary\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape.svg\" class=\"shape-green-pink\" alt=\"\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape-blue.svg\" class=\"shape-green-blue\" alt=\"\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape-orange.svg\" class=\"shape-green-orange\" alt=\"\">\n                    \n                    <b>Sous-titres professionnels<\/b>\n                    <p>Les sous-titres (traduits ou non) sont cr\u00e9\u00e9s et \u00e9dit\u00e9s par nos transcripteurs.<\/p>\n                <\/div>\n                \n            <\/div>\n        <\/div>\n    <\/a>\n    \n<\/div>                            <\/div>\n                                                    <div class=\"cell medium-6 large-4\">\n                                <div class=\"cell\">\n    <a href=\"https:\/\/wp-staging.amberscript.com\/fr\/produits\/api-modeles-personnalises\/\">\n        <div class=\"flip-card\">\n            <div class=\"flip-card-inner\">\n                <div class=\"flip-card-front\">\n                <div class=\"product-item\">\n                    <b>API &#038; Mod\u00e8les personnalis\u00e9s<\/b>\n                    <div class=\"button primary black\">\n                        En savoir plus                    <\/div>\n                <\/div>\n                <\/div>\n                \n                <div class=\"flip-card-back theme-background-secondary\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape.svg\" class=\"shape-green-pink\" alt=\"\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape-blue.svg\" class=\"shape-green-blue\" alt=\"\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape-orange.svg\" class=\"shape-green-orange\" alt=\"\">\n                    \n                    <b>API &#038; Mod\u00e8les personnalis\u00e9s<\/b>\n                    <p>Ajoutez notre API et\/ou demandez un mod\u00e8le.<\/p>\n                <\/div>\n                \n            <\/div>\n        <\/div>\n    <\/a>\n    \n<\/div>                            <\/div>\n                                                    <div class=\"cell medium-6 large-4\">\n                                <div class=\"cell\">\n    <a href=\"https:\/\/wp-staging.amberscript.com\/fr\/produits\/solutions-dentreprise\/\">\n        <div class=\"flip-card\">\n            <div class=\"flip-card-inner\">\n                <div class=\"flip-card-front\">\n                <div class=\"product-item\">\n                    <b>Solutions d&rsquo;entreprise<\/b>\n                    <div class=\"button primary black\">\n                        En savoir plus                    <\/div>\n                <\/div>\n                <\/div>\n                \n                <div class=\"flip-card-back theme-background-secondary\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape.svg\" class=\"shape-green-pink\" alt=\"\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape-blue.svg\" class=\"shape-green-blue\" alt=\"\">\n                    <img decoding=\"async\" src=\"https:\/\/wp-staging.amberscript.com\/wp-content\/themes\/amberscript\/img\/card-shape-orange.svg\" class=\"shape-green-orange\" alt=\"\">\n                    \n                    <b>Solutions d&rsquo;entreprise<\/b>\n                    <p>Remises sur le volume, licence multi-utilisateurs, int\u00e9gration API et autres solution d&rsquo;entreprises.<\/p>\n                <\/div>\n                \n            <\/div>\n        <\/div>\n    <\/a>\n    \n<\/div>                            <\/div>\n                                                            <\/div>\n\n                <\/div>\n\n            <\/div>\n\n        <\/div>\n    <\/div>    <\/div>\n\n\n\n    \n            <div class=\"block banner background green padding larger-padding\">\n                            <div class=\"banner-shape\">\n                    <svg width=\"451px\" height=\"240px\" viewBox=\"0 0 451 240\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\">\n    <title>Group 3<\/title>\n    <g id=\"3.-Home-&amp;-about-us-,pricing\" stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\">\n        <g id=\"Careers\/jobs\" transform=\"translate(-1240.000000, -211.000000)\" fill=\"#FAAA28\">\n            <g id=\"Group-3\" transform=\"translate(1240.000000, 211.000000)\">\n                <path d=\"M3.94006881,183.858011 C6.50523543,181.287277 9.63996752,180.000637 13.3459627,180.000637 L16.7650531,180.000637 C20.4651065,180.000637 23.6049316,181.287277 26.1700982,183.858011 C28.7361136,186.428746 30.0178481,189.57066 30.0178481,193.287998 L30.0178481,196.71423 C30.0178481,200.425627 31.3012803,203.573482 33.8672957,206.145065 C36.4299158,208.714951 39.5637991,210.00244 43.2697943,210.00244 L46.6914312,210.00244 C50.3923334,210.00244 53.5321585,208.714951 56.0947786,206.145065 C58.6599452,203.573482 59.945075,200.425627 59.945075,196.71423 L59.945075,193.287998 C59.945075,189.57066 61.2259607,186.428746 63.7911273,183.858011 C66.3571428,181.287277 69.4884795,180.000637 73.1970212,180.000637 L76.6161116,180.000637 C80.316165,180.000637 83.45599,181.287277 86.0220055,183.858011 C88.5846256,186.428746 89.8689066,189.57066 89.8689066,193.287998 L89.8689066,196.71423 C89.8689066,200.425627 91.1497923,203.573482 93.7158077,206.145065 C96.2809743,208.714951 99.4123111,210.00244 103.121702,210.00244 L106.539943,210.00244 C110.239997,210.00244 113.38067,208.714951 115.945837,206.145065 C118.511853,203.573482 119.792738,200.425627 119.792738,196.71423 L119.792738,193.287998 C119.792738,189.57066 121.077019,186.428746 123.639639,183.858011 C126.205655,181.287277 129.339538,180.000637 133.045533,180.000637 L136.46717,180.000637 C140.167223,180.000637 143.304502,181.287277 145.870518,183.858011 C148.435684,186.428746 149.71657,189.57066 149.71657,193.287998 L149.71657,196.71423 C149.71657,200.425627 151.000851,203.573482 153.566866,206.145065 C156.132033,208.714951 159.26337,210.00244 162.970214,210.00244 L166.391002,210.00244 C170.091904,210.00244 173.231729,208.714951 175.796896,206.145065 C178.359516,203.573482 179.643797,200.425627 179.643797,196.71423 L179.643797,193.287998 C179.643797,189.57066 180.925531,186.428746 183.490698,183.858011 C186.055864,181.287277 189.18805,180.000637 192.896592,180.000637 L196.315682,180.000637 C200.015735,180.000637 203.155561,181.287277 205.721576,183.858011 C208.286743,186.428746 209.568477,189.57066 209.568477,193.287998 L209.568477,196.71423 C209.568477,200.425627 210.849363,203.573482 213.415378,206.145065 C215.980545,208.714951 219.115277,210.00244 222.820423,210.00244 L226.239514,210.00244 C229.940416,210.00244 233.080241,208.714951 235.645408,206.145065 C238.211423,203.573482 239.492309,200.425627 239.492309,196.71423 L239.492309,193.287998 C239.492309,189.57066 240.77659,186.428746 243.341756,183.858011 C245.904376,181.287277 249.039108,180.000637 252.745104,180.000637 L256.166741,180.000637 C259.866794,180.000637 263.007468,181.287277 265.570088,183.858011 C268.135255,186.428746 269.419536,189.57066 269.419536,193.287998 L269.419536,196.71423 C269.419536,200.425627 270.700421,203.573482 273.266437,206.145065 C275.831603,208.714951 278.96294,210.00244 282.672331,210.00244 L436.840373,210.00244 C440.540426,210.00244 443.6811,211.285685 446.246267,213.857269 C448.812282,216.430549 450.093168,219.569918 450.093168,223.286407 L450.093168,226.716033 C450.093168,230.424035 448.812282,233.571891 446.246267,236.142625 C443.6811,238.714208 440.540426,240 436.840373,240 L282.672331,240 C278.96294,240 275.831603,238.714208 273.266437,236.142625 C270.700421,233.571891 269.419536,230.424035 269.419536,226.716033 L269.419536,223.286407 C269.419536,219.569918 268.135255,216.430549 265.570088,213.857269 C263.007468,211.285685 259.866794,210.00244 256.166741,210.00244 L252.745104,210.00244 C249.039108,210.00244 245.904376,211.285685 243.341756,213.857269 C240.77659,216.430549 239.492309,219.569918 239.492309,223.286407 L239.492309,226.716033 C239.492309,230.424035 238.211423,233.571891 235.645408,236.142625 C233.080241,238.714208 229.940416,240 226.239514,240 L222.820423,240 C219.115277,240 215.980545,238.714208 213.415378,236.142625 C210.849363,233.571891 209.568477,230.424035 209.568477,226.716033 L209.568477,223.286407 C209.568477,219.569918 208.286743,216.430549 205.721576,213.857269 C203.155561,211.285685 200.015735,210.00244 196.315682,210.00244 L192.896592,210.00244 C189.18805,210.00244 186.055864,211.285685 183.490698,213.857269 C180.925531,216.430549 179.643797,219.569918 179.643797,223.286407 L179.643797,226.716033 C179.643797,230.424035 178.359516,233.571891 175.796896,236.142625 C173.231729,238.714208 170.091904,240 166.391002,240 L162.970214,240 C159.26337,240 156.132033,238.714208 153.566866,236.142625 C151.000851,233.571891 149.71657,230.424035 149.71657,226.716033 L149.71657,223.286407 C149.71657,219.569918 148.435684,216.430549 145.870518,213.857269 C143.304502,211.285685 140.167223,210.00244 136.46717,210.00244 L133.045533,210.00244 C129.339538,210.00244 126.205655,211.285685 123.639639,213.857269 C121.077019,216.430549 119.792738,219.569918 119.792738,223.286407 L119.792738,226.716033 C119.792738,230.424035 118.511853,233.571891 115.945837,236.142625 C113.38067,238.714208 110.239997,240 106.539943,240 L103.121702,240 C99.4123111,240 96.2809743,238.714208 93.7158077,236.142625 C91.1497923,233.571891 89.8689066,230.424035 89.8689066,226.716033 L89.8689066,223.286407 C89.8689066,219.569918 88.5846256,216.430549 86.0220055,213.857269 C83.45599,211.285685 80.316165,210.00244 76.6161116,210.00244 L73.1970212,210.00244 C69.4884795,210.00244 66.3571428,211.285685 63.7911273,213.857269 C61.2259607,216.430549 59.945075,219.569918 59.945075,223.286407 L59.945075,226.716033 C59.945075,230.424035 58.6599452,233.571891 56.0947786,236.142625 C53.5321585,238.714208 50.3923334,240 46.6914312,240 L43.2697943,240 C39.5637991,240 36.4299158,238.714208 33.8672957,236.142625 C31.3012803,233.571891 30.0178481,230.424035 30.0178481,226.716033 L30.0178481,223.286407 C30.0178481,219.569918 28.7361136,216.430549 26.1700982,213.857269 C23.6049316,211.285685 20.4651065,210.00244 16.7650531,210.00244 L13.3459627,210.00244 C9.63996752,210.00244 6.50523543,208.714951 3.94006881,206.145065 C1.37490218,203.573482 0.0931677019,200.425627 0.0931677019,196.71423 L0.0931677019,193.287998 C0.0931677019,189.57066 1.37490218,186.428746 3.94006881,183.858011 M3.94006881,123.857799 C6.50523543,121.287065 9.63996752,120.000424 13.3459627,120.000424 L16.7650531,120.000424 C20.4651065,120.000424 23.6049316,121.287065 26.1700982,123.857799 C28.7361136,126.428534 30.0178481,129.571297 30.0178481,133.287786 L30.0178481,136.714017 C30.0178481,140.425415 31.3012803,143.57327 33.8672957,146.144004 C36.4299158,148.715588 39.5637991,150.001379 43.2697943,150.001379 L46.6914312,150.001379 C50.3923334,150.001379 53.5321585,148.715588 56.0947786,146.144004 C58.6599452,143.57327 59.945075,140.425415 59.945075,136.714017 L59.945075,133.287786 C59.945075,129.571297 61.2259607,126.428534 63.7911273,123.857799 C66.3571428,121.287065 69.4884795,120.000424 73.1970212,120.000424 L76.6161116,120.000424 C80.316165,120.000424 83.45599,121.287065 86.0220055,123.857799 C88.5846256,126.428534 89.8689066,129.571297 89.8689066,133.287786 L89.8689066,136.714017 C89.8689066,140.425415 91.1497923,143.57327 93.7158077,146.144004 C96.2809743,148.715588 99.4123111,150.001379 103.121702,150.001379 L106.539943,150.001379 C110.239997,150.001379 113.38067,148.715588 115.945837,146.144004 C118.511853,143.57327 119.792738,140.425415 119.792738,136.714017 L119.792738,133.287786 C119.792738,129.571297 121.077019,126.428534 123.639639,123.857799 C126.205655,121.287065 129.339538,120.000424 133.045533,120.000424 L136.46717,120.000424 C140.167223,120.000424 143.304502,121.287065 145.870518,123.857799 C148.435684,126.428534 149.71657,129.571297 149.71657,133.287786 L149.71657,136.714017 C149.71657,140.425415 151.000851,143.57327 153.566866,146.144004 C156.132033,148.715588 159.26337,150.001379 162.970214,150.001379 L166.391002,150.001379 C170.091904,150.001379 173.231729,148.715588 175.796896,146.144004 C178.359516,143.57327 179.643797,140.425415 179.643797,136.714017 L179.643797,133.287786 C179.643797,129.571297 180.925531,126.428534 183.490698,123.857799 C186.055864,121.287065 189.18805,120.000424 192.896592,120.000424 L196.315682,120.000424 C200.015735,120.000424 203.155561,121.287065 205.721576,123.857799 C208.286743,126.428534 209.568477,129.571297 209.568477,133.287786 L209.568477,136.714017 C209.568477,140.425415 210.849363,143.57327 213.415378,146.144004 C215.980545,148.715588 219.115277,150.001379 222.820423,150.001379 L226.239514,150.001379 C229.940416,150.001379 233.080241,148.715588 235.645408,146.144004 C238.211423,143.57327 239.492309,140.425415 239.492309,136.714017 L239.492309,133.287786 C239.492309,129.571297 240.77659,126.428534 243.341756,123.857799 C245.904376,121.287065 249.039108,120.000424 252.745104,120.000424 L256.166741,120.000424 C259.866794,120.000424 263.007468,121.287065 265.570088,123.857799 C268.135255,126.428534 269.419536,129.571297 269.419536,133.287786 L269.419536,136.714017 C269.419536,140.425415 270.700421,143.57327 273.266437,146.144004 C275.831603,148.715588 278.96294,150.001379 282.672331,150.001379 L436.840373,150.001379 C440.540426,150.001379 443.6811,151.285473 446.246267,153.858754 C448.812282,156.430337 450.093168,159.569705 450.093168,163.287043 L450.093168,166.715821 C450.093168,170.424672 448.812282,173.572527 446.246267,176.143262 C443.6811,178.716542 440.540426,180.000637 436.840373,180.000637 L282.672331,180.000637 C278.96294,180.000637 275.831603,178.716542 273.266437,176.143262 C270.700421,173.572527 269.419536,170.424672 269.419536,166.715821 L269.419536,163.287043 C269.419536,159.569705 268.135255,156.430337 265.570088,153.858754 C263.007468,151.285473 259.866794,150.001379 256.166741,150.001379 L252.745104,150.001379 C249.039108,150.001379 245.904376,151.285473 243.341756,153.858754 C240.77659,156.430337 239.492309,159.569705 239.492309,163.287043 L239.492309,166.715821 C239.492309,170.424672 238.211423,173.572527 235.645408,176.143262 C233.080241,178.716542 229.940416,180.000637 226.239514,180.000637 L222.820423,180.000637 C219.115277,180.000637 215.980545,178.716542 213.415378,176.143262 C210.849363,173.572527 209.568477,170.424672 209.568477,166.715821 L209.568477,163.287043 C209.568477,159.569705 208.286743,156.430337 205.721576,153.858754 C203.155561,151.285473 200.015735,150.001379 196.315682,150.001379 L192.896592,150.001379 C189.18805,150.001379 186.055864,151.285473 183.490698,153.858754 C180.925531,156.430337 179.643797,159.569705 179.643797,163.287043 L179.643797,166.715821 C179.643797,170.424672 178.359516,173.572527 175.796896,176.143262 C173.231729,178.716542 170.091904,180.000637 166.391002,180.000637 L162.970214,180.000637 C159.26337,180.000637 156.132033,178.716542 153.566866,176.143262 C151.000851,173.572527 149.71657,170.424672 149.71657,166.715821 L149.71657,163.287043 C149.71657,159.569705 148.435684,156.430337 145.870518,153.858754 C143.304502,151.285473 140.167223,150.001379 136.46717,150.001379 L133.045533,150.001379 C129.339538,150.001379 126.205655,151.285473 123.639639,153.858754 C121.077019,156.430337 119.792738,159.569705 119.792738,163.287043 L119.792738,166.715821 C119.792738,170.424672 118.511853,173.572527 115.945837,176.143262 C113.38067,178.716542 110.239997,180.000637 106.539943,180.000637 L103.121702,180.000637 C99.4123111,180.000637 96.2809743,178.716542 93.7158077,176.143262 C91.1497923,173.572527 89.8689066,170.424672 89.8689066,166.715821 L89.8689066,163.287043 C89.8689066,159.569705 88.5846256,156.430337 86.0220055,153.858754 C83.45599,151.285473 80.316165,150.001379 76.6161116,150.001379 L73.1970212,150.001379 C69.4884795,150.001379 66.3571428,151.285473 63.7911273,153.858754 C61.2259607,156.430337 59.945075,159.569705 59.945075,163.287043 L59.945075,166.715821 C59.945075,170.424672 58.6599452,173.572527 56.0947786,176.143262 C53.5321585,178.716542 50.3923334,180.000637 46.6914312,180.000637 L43.2697943,180.000637 C39.5637991,180.000637 36.4299158,178.716542 33.8672957,176.143262 C31.3012803,173.572527 30.0178481,170.424672 30.0178481,166.715821 L30.0178481,163.287043 C30.0178481,159.569705 28.7361136,156.430337 26.1700982,153.858754 C23.6049316,151.285473 20.4651065,150.001379 16.7650531,150.001379 L13.3459627,150.001379 C9.63996752,150.001379 6.50523543,148.715588 3.94006881,146.144004 C1.37490218,143.57327 0.0931677019,140.425415 0.0931677019,136.714017 L0.0931677019,133.287786 C0.0931677019,129.571297 1.37490218,126.428534 3.94006881,123.857799 M3.94006881,63.8575869 C6.50523543,61.2868525 9.63996752,60.0002122 13.3459627,60.0002122 L16.7650531,60.0002122 C20.4651065,60.0002122 23.6049316,61.2868525 26.1700982,63.8575869 C28.7361136,66.4291701 30.0178481,69.5710845 30.0178481,73.2875739 L30.0178481,76.714654 C30.0178481,80.4252024 31.3012803,83.5739065 33.8672957,86.1437922 C36.4299158,88.7145267 39.5637991,90.0020157 43.2697943,90.0020157 L46.6914312,90.0020157 C50.3923334,90.0020157 53.5321585,88.7145267 56.0947786,86.1437922 C58.6599452,83.5739065 59.945075,80.4252024 59.945075,76.714654 L59.945075,73.2875739 C59.945075,69.5710845 61.2259607,66.4291701 63.7911273,63.8575869 C66.3571428,61.2868525 69.4884795,60.0002122 73.1970212,60.0002122 L76.6161116,60.0002122 C80.316165,60.0002122 83.45599,61.2868525 86.0220055,63.8575869 C88.5846256,66.4291701 89.8689066,69.5710845 89.8689066,73.2875739 L89.8689066,76.714654 C89.8689066,80.4252024 91.1497923,83.5739065 93.7158077,86.1437922 C96.2809743,88.7145267 99.4123111,90.0020157 103.121702,90.0020157 L106.539943,90.0020157 C110.239997,90.0020157 113.38067,88.7145267 115.945837,86.1437922 C118.511853,83.5739065 119.792738,80.4252024 119.792738,76.714654 L119.792738,73.2875739 C119.792738,69.5710845 121.077019,66.4291701 123.639639,63.8575869 C126.205655,61.2868525 129.339538,60.0002122 133.045533,60.0002122 L136.46717,60.0002122 C140.167223,60.0002122 143.304502,61.2868525 145.870518,63.8575869 C148.435684,66.4291701 149.71657,69.5710845 149.71657,73.2875739 L149.71657,76.714654 C149.71657,80.4252024 151.000851,83.5739065 153.566866,86.1437922 C156.132033,88.7145267 159.26337,90.0020157 162.970214,90.0020157 L166.391002,90.0020157 C170.091904,90.0020157 173.231729,88.7145267 175.796896,86.1437922 C178.359516,83.5739065 179.643797,80.4252024 179.643797,76.714654 L179.643797,73.2875739 C179.643797,69.5710845 180.925531,66.4291701 183.490698,63.8575869 C186.055864,61.2868525 189.18805,60.0002122 192.896592,60.0002122 L196.315682,60.0002122 C200.015735,60.0002122 203.155561,61.2868525 205.721576,63.8575869 C208.286743,66.4291701 209.568477,69.5710845 209.568477,73.2875739 L209.568477,76.714654 C209.568477,80.4252024 210.849363,83.5739065 213.415378,86.1437922 C215.980545,88.7145267 219.115277,90.0020157 222.820423,90.0020157 L226.239514,90.0020157 C229.940416,90.0020157 233.080241,88.7145267 235.645408,86.1437922 C238.211423,83.5739065 239.492309,80.4252024 239.492309,76.714654 L239.492309,73.2875739 C239.492309,69.5710845 240.77659,66.4291701 243.341756,63.8575869 C245.904376,61.2868525 249.039108,60.0002122 252.745104,60.0002122 L256.166741,60.0002122 C259.866794,60.0002122 263.007468,61.2868525 265.570088,63.8575869 C268.135255,66.4291701 269.419536,69.5710845 269.419536,73.2875739 L269.419536,76.714654 C269.419536,80.4252024 270.700421,83.5739065 273.266437,86.1437922 C275.831603,88.7145267 278.96294,90.0020157 282.672331,90.0020157 L436.840373,90.0020157 C440.540426,90.0020157 443.6811,91.2861098 446.246267,93.8593904 C448.812282,96.4301249 450.093168,99.5703419 450.093168,103.285983 L450.093168,106.715609 C450.093168,110.42446 448.812282,113.572315 446.246267,116.14305 C443.6811,118.71633 440.540426,120.000424 436.840373,120.000424 L282.672331,120.000424 C278.96294,120.000424 275.831603,118.71633 273.266437,116.14305 C270.700421,113.572315 269.419536,110.42446 269.419536,106.715609 L269.419536,103.285983 C269.419536,99.5703419 268.135255,96.4301249 265.570088,93.8593904 C263.007468,91.2861098 259.866794,90.0020157 256.166741,90.0020157 L252.745104,90.0020157 C249.039108,90.0020157 245.904376,91.2861098 243.341756,93.8593904 C240.77659,96.4301249 239.492309,99.5703419 239.492309,103.285983 L239.492309,106.715609 C239.492309,110.42446 238.211423,113.572315 235.645408,116.14305 C233.080241,118.71633 229.940416,120.000424 226.239514,120.000424 L222.820423,120.000424 C219.115277,120.000424 215.980545,118.71633 213.415378,116.14305 C210.849363,113.572315 209.568477,110.42446 209.568477,106.715609 L209.568477,103.285983 C209.568477,99.5703419 208.286743,96.4301249 205.721576,93.8593904 C203.155561,91.2861098 200.015735,90.0020157 196.315682,90.0020157 L192.896592,90.0020157 C189.18805,90.0020157 186.055864,91.2861098 183.490698,93.8593904 C180.925531,96.4301249 179.643797,99.5703419 179.643797,103.285983 L179.643797,106.715609 C179.643797,110.42446 178.359516,113.572315 175.796896,116.14305 C173.231729,118.71633 170.091904,120.000424 166.391002,120.000424 L162.970214,120.000424 C159.26337,120.000424 156.132033,118.71633 153.566866,116.14305 C151.000851,113.572315 149.71657,110.42446 149.71657,106.715609 L149.71657,103.285983 C149.71657,99.5703419 148.435684,96.4301249 145.870518,93.8593904 C143.304502,91.2861098 140.167223,90.0020157 136.46717,90.0020157 L133.045533,90.0020157 C129.339538,90.0020157 126.205655,91.2861098 123.639639,93.8593904 C121.077019,96.4301249 119.792738,99.5703419 119.792738,103.285983 L119.792738,106.715609 C119.792738,110.42446 118.511853,113.572315 115.945837,116.14305 C113.38067,118.71633 110.239997,120.000424 106.539943,120.000424 L103.121702,120.000424 C99.4123111,120.000424 96.2809743,118.71633 93.7158077,116.14305 C91.1497923,113.572315 89.8689066,110.42446 89.8689066,106.715609 L89.8689066,103.285983 C89.8689066,99.5703419 88.5846256,96.4301249 86.0220055,93.8593904 C83.45599,91.2861098 80.316165,90.0020157 76.6161116,90.0020157 L73.1970212,90.0020157 C69.4884795,90.0020157 66.3571428,91.2861098 63.7911273,93.8593904 C61.2259607,96.4301249 59.945075,99.5703419 59.945075,103.285983 L59.945075,106.715609 C59.945075,110.42446 58.6599452,113.572315 56.0947786,116.14305 C53.5321585,118.71633 50.3923334,120.000424 46.6914312,120.000424 L43.2697943,120.000424 C39.5637991,120.000424 36.4299158,118.71633 33.8672957,116.14305 C31.3012803,113.572315 30.0178481,110.42446 30.0178481,106.715609 L30.0178481,103.285983 C30.0178481,99.5703419 28.7361136,96.4301249 26.1700982,93.8593904 C23.6049316,91.2861098 20.4651065,90.0020157 16.7650531,90.0020157 L13.3459627,90.0020157 C9.63996752,90.0020157 6.50523543,88.7145267 3.94006881,86.1437922 C1.37490218,83.5739065 0.0931677019,80.4252024 0.0931677019,76.714654 L0.0931677019,73.2875739 C0.0931677019,69.5710845 1.37490218,66.4291701 3.94006881,63.8575869 M13.3459627,0 L16.7650531,0 C20.4651065,0 23.6049316,1.28664029 26.1700982,3.85737474 C28.7361136,6.43065531 30.0178481,9.57087237 30.0178481,13.2873617 L30.0178481,16.7144418 C30.0178481,20.4258389 31.3012803,23.5736943 33.8672957,26.1444288 C36.4299158,28.7143145 39.5637991,30.0018035 43.2697943,30.0018035 L46.6914312,30.0018035 C50.3923334,30.0018035 53.5321585,28.7143145 56.0947786,26.1444288 C58.6599452,23.5736943 59.945075,20.4258389 59.945075,16.7144418 L59.945075,13.2873617 C59.945075,9.57087237 61.2259607,6.43065531 63.7911273,3.85737474 C66.3571428,1.28664029 69.4884795,0 73.1970212,0 L76.6161116,0 C80.316165,0 83.45599,1.28664029 86.0220055,3.85737474 C88.5846256,6.43065531 89.8689066,9.57087237 89.8689066,13.2873617 L89.8689066,16.7144418 C89.8689066,20.4258389 91.1497923,23.5736943 93.7158077,26.1444288 C96.2809743,28.7143145 99.4123111,30.0018035 103.121702,30.0018035 L106.539943,30.0018035 C110.239997,30.0018035 113.38067,28.7143145 115.945837,26.1444288 C118.511853,23.5736943 119.792738,20.4258389 119.792738,16.7144418 L119.792738,13.2873617 C119.792738,9.57087237 121.077019,6.43065531 123.639639,3.85737474 C126.205655,1.28664029 129.339538,0 133.045533,0 L136.46717,0 C140.167223,0 143.304502,1.28664029 145.870518,3.85737474 C148.435684,6.43065531 149.71657,9.57087237 149.71657,13.2873617 L149.71657,16.7144418 C149.71657,20.4258389 151.000851,23.5736943 153.566866,26.1444288 C156.132033,28.7143145 159.26337,30.0018035 162.970214,30.0018035 L166.391002,30.0018035 C170.091904,30.0018035 173.231729,28.7143145 175.796896,26.1444288 C178.359516,23.5736943 179.643797,20.4258389 179.643797,16.7144418 L179.643797,13.2873617 C179.643797,9.57087237 180.925531,6.43065531 183.490698,3.85737474 C186.055864,1.28664029 189.18805,0 192.896592,0 L196.315682,0 C200.015735,0 203.155561,1.28664029 205.721576,3.85737474 C208.286743,6.43065531 209.568477,9.57087237 209.568477,13.2873617 L209.568477,16.7144418 C209.568477,20.4258389 210.849363,23.5736943 213.415378,26.1444288 C215.980545,28.7143145 219.115277,30.0018035 222.820423,30.0018035 L226.239514,30.0018035 C229.940416,30.0018035 233.080241,28.7143145 235.645408,26.1444288 C238.211423,23.5736943 239.492309,20.4258389 239.492309,16.7144418 L239.492309,13.2873617 C239.492309,9.57087237 240.77659,6.43065531 243.341756,3.85737474 C245.904376,1.28664029 249.039108,0 252.745104,0 L256.166741,0 C259.866794,0 263.007468,1.28664029 265.570088,3.85737474 C268.135255,6.43065531 269.419536,9.57087237 269.419536,13.2873617 L269.419536,16.7144418 C269.419536,20.4258389 270.700421,23.5736943 273.266437,26.1444288 C275.831603,28.7143145 278.96294,30.0018035 282.672331,30.0018035 L436.840373,30.0018035 C440.540426,30.0018035 443.6811,31.285049 446.246267,33.8591782 C448.812282,36.4299127 450.093168,39.569281 450.093168,43.2857704 L450.093168,46.7153966 C450.093168,50.4233989 448.812282,53.572103 446.246267,56.1428374 C443.6811,58.716118 440.540426,60.0002122 436.840373,60.0002122 L282.672331,60.0002122 C278.96294,60.0002122 275.831603,58.716118 273.266437,56.1428374 C270.700421,53.572103 269.419536,50.4233989 269.419536,46.7153966 L269.419536,43.2857704 C269.419536,39.569281 268.135255,36.4299127 265.570088,33.8591782 C263.007468,31.285049 259.866794,30.0018035 256.166741,30.0018035 L252.745104,30.0018035 C249.039108,30.0018035 245.904376,31.285049 243.341756,33.8591782 C240.77659,36.4299127 239.492309,39.569281 239.492309,43.2857704 L239.492309,46.7153966 C239.492309,50.4233989 238.211423,53.572103 235.645408,56.1428374 C233.080241,58.716118 229.940416,60.0002122 226.239514,60.0002122 L222.820423,60.0002122 C219.115277,60.0002122 215.980545,58.716118 213.415378,56.1428374 C210.849363,53.572103 209.568477,50.4233989 209.568477,46.7153966 L209.568477,43.2857704 C209.568477,39.569281 208.286743,36.4299127 205.721576,33.8591782 C203.155561,31.285049 200.015735,30.0018035 196.315682,30.0018035 L192.896592,30.0018035 C189.18805,30.0018035 186.055864,31.285049 183.490698,33.8591782 C180.925531,36.4299127 179.643797,39.569281 179.643797,43.2857704 L179.643797,46.7153966 C179.643797,50.4233989 178.359516,53.572103 175.796896,56.1428374 C173.231729,58.716118 170.091904,60.0002122 166.391002,60.0002122 L162.970214,60.0002122 C159.26337,60.0002122 156.132033,58.716118 153.566866,56.1428374 C151.000851,53.572103 149.71657,50.4233989 149.71657,46.7153966 L149.71657,43.2857704 C149.71657,39.569281 148.435684,36.4299127 145.870518,33.8591782 C143.304502,31.285049 140.167223,30.0018035 136.46717,30.0018035 L133.045533,30.0018035 C129.339538,30.0018035 126.205655,31.285049 123.639639,33.8591782 C121.077019,36.4299127 119.792738,39.569281 119.792738,43.2857704 L119.792738,46.7153966 C119.792738,50.4233989 118.511853,53.572103 115.945837,56.1428374 C113.38067,58.716118 110.239997,60.0002122 106.539943,60.0002122 L103.121702,60.0002122 C99.4123111,60.0002122 96.2809743,58.716118 93.7158077,56.1428374 C91.1497923,53.572103 89.8689066,50.4233989 89.8689066,46.7153966 L89.8689066,43.2857704 C89.8689066,39.569281 88.5846256,36.4299127 86.0220055,33.8591782 C83.45599,31.285049 80.316165,30.0018035 76.6161116,30.0018035 L73.1970212,30.0018035 C69.4884795,30.0018035 66.3571428,31.285049 63.7911273,33.8591782 C61.2259607,36.4299127 59.945075,39.569281 59.945075,43.2857704 L59.945075,46.7153966 C59.945075,50.4233989 58.6599452,53.572103 56.0947786,56.1428374 C53.5321585,58.716118 50.3923334,60.0002122 46.6914312,60.0002122 L43.2697943,60.0002122 C39.5637991,60.0002122 36.4299158,58.716118 33.8672957,56.1428374 C31.3012803,53.572103 30.0178481,50.4233989 30.0178481,46.7153966 L30.0178481,43.2857704 C30.0178481,39.569281 28.7361136,36.4299127 26.1700982,33.8591782 C23.6049316,31.285049 20.4651065,30.0018035 16.7650531,30.0018035 L13.3459627,30.0018035 C9.63996752,30.0018035 6.50523543,28.7143145 3.94006881,26.1444288 C1.37490218,23.5736943 0.0931677019,20.4258389 0.0931677019,16.7144418 L0.0931677019,13.2873617 C0.0931677019,9.57087237 1.37490218,6.43065531 3.94006881,3.85737474 C6.50523543,1.28664029 9.63996752,0 13.3459627,0 Z\" id=\"Fill-1\"><\/path>\n            <\/g>\n        <\/g>\n    <\/g>\n<\/svg>                <\/div>\n                        <div class=\"grid-container\">\n                <div class=\"grid-x align-middle align-center\">\n                    <div class=\"cell medium-10 text-center\">\n\n                          \n                                    <h2 class=\"inherit\">Nous rendons l&rsquo;audio accessible<\/h2>\n                    \n                                                        <a class=\"button theme-background-primary\" href=\"https:\/\/app.amberscript.com\/register?lang=fr\" target=\"_self\" rel=\"noopener\">Essayez gratuitement<\/a>\n                                            <\/div>\n                \n                <\/div>\n            <\/div>\n        <\/div>\n    \n","protected":false},"excerpt":{"rendered":"","protected":false},"author":70,"featured_media":0,"parent":22799,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-80636","page","type-page","status-publish","hentry"],"acf":{"show_footer":true,"header_dark_mode":false},"_links":{"self":[{"href":"https:\/\/wp-staging.amberscript.com\/fr\/wp-json\/wp\/v2\/pages\/80636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp-staging.amberscript.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wp-staging.amberscript.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wp-staging.amberscript.com\/fr\/wp-json\/wp\/v2\/users\/70"}],"replies":[{"embeddable":true,"href":"https:\/\/wp-staging.amberscript.com\/fr\/wp-json\/wp\/v2\/comments?post=80636"}],"version-history":[{"count":0,"href":"https:\/\/wp-staging.amberscript.com\/fr\/wp-json\/wp\/v2\/pages\/80636\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/wp-staging.amberscript.com\/fr\/wp-json\/wp\/v2\/pages\/22799"}],"wp:attachment":[{"href":"https:\/\/wp-staging.amberscript.com\/fr\/wp-json\/wp\/v2\/media?parent=80636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}